{"id":10712,"date":"2016-12-19T07:24:21","date_gmt":"2016-12-19T06:24:21","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=10712"},"modified":"2016-12-02T15:25:41","modified_gmt":"2016-12-02T14:25:41","slug":"ich-achte-auf-gott-4-montagmorgenimpuls-im-advent","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/ich-achte-auf-gott-4-montagmorgenimpuls-im-advent\/","title":{"rendered":"\u201eIch achte auf Gott!\u201c  &#8211;  4. Montagmorgenimpuls im Advent"},"content":{"rendered":"<a attid=\"10713\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/12\/04.jpg\" rel=\"lightbox[10712]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/12\/04-300x225.jpg\" alt=\"04\" width=\"300\" height=\"225\" class=\"alignright size-medium wp-image-10713\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/12\/04-300x225.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/12\/04-768x576.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/12\/04-1024x768.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/12\/04-440x330.jpg 440w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/12\/04.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><strong>19. Dezember 2016<\/strong>.<br>\r\n\r\n<em><strong><p>1. Lied <\/p><p><\/strong><\/em>\r\n<em><strong>\r\n2. Geschichte<\/strong><\/em><br>\r\nDer Himmel war ratlos. Keiner der Himmlischen wusste mehr, wie man den Menschen beikommen k\u00f6nnte. Die Irdischen waren f\u00fcr die Geheimnisse des Himmels taub und blind geworden. Die Tr\u00e4ume waren erloschen. Dieser \u00f6de Zustand durfte nicht um sich greifen. So blieb den Himmlischen nichts anderes \u00fcbrig, als \u00fcber m\u00f6gliche Wege miteinander zu verhandeln.<br>\r\nEine Gruppe wies darauf hin, dass fr\u00fcher gro\u00dfe Naturkatastrophen die irdischen am ehesten nachdenklich gestimmt h\u00e4tten. Doch dagegen wurde einhellig Einspruch erhoben: \u201eStrafaktionen k\u00f6nnen doch nicht himmlische Mittel sein!\u201c<br>\r\nDa w\u00e4re es doch sinnvoller, meinte eine andere Gruppe, in voller Ausr\u00fcstung den Irdischen gegen\u00fcberzutreten und sie mit Glanz und Gloria zu \u00fcberw\u00e4ltigen, dass keiner mehr die Augen verschlie\u00dfen k\u00f6nne.<br>\r\nAber die J\u00fcngeren waren solchen Machtdemonstrationen gegen\u00fcber v\u00f6llig abgeneigt: \u201eWir werden wohl im Moment Eindruck machen, aber wenn sie uns nicht mehr sehen, bleiben ihnen nur unsere himmlischen Heere in Erinnerung, und sie werden nicht z\u00f6gern, unseren Auftritt nachzuahmen und selber Heere aufzustellen.\u201c<br>\r\nBisher hatte sich eine weitere Gruppe zur\u00fcckgehalten. Doch ihren Mienen war abzulesen, dass sie mit keinem Vorschlag einverstanden waren. \u201eWir seit Wochen den irdischen Markt erforscht. Man muss wissen, was sie erwarten und welche Bed\u00fcrfnisse sie haben. Danach m\u00fcssen wir unsere Absichten richten, sonst bleibt es ein Angebot ohne Nachfrage.\u201c<br>\r\nPl\u00f6tzlich wurde es still. Gabriel war zu ihnen getreten. Er war bei IHM gewesen. Nun stand er unter ihnen und strahlte sie an. Dann sagte er: \u201eEin Kind!\u201c<br>\r\nUnd als ihn alle sprachlos anstarrten, wiederholte er: \u201eEin Kind. Er gibt ihnen ein Kind. Das ist Seine Antwort auf die Entfremdung der Menschen.\u201c<br>\r\n\u201eEin Kind? Ein Kind!\u201c, riefen alle durcheinander, und es klang staunend und erschrocken, bewundernd und abwehrend zugleich. Ein Kind \u2013 wie g\u00f6ttlich, wie gew\u00f6hnlich, wie einfach, wie unverst\u00e4ndlich!<br>\r\nAls erstes brach es aus jenen heraus, die die Irdischen erforscht hatten: \u201eAber sie wollen das Kind doch nicht. Sie wollen \u00fcberhaupt keine Kinder mehr. Kinder sind unerw\u00fcnscht! Sie haben keinen Platz f\u00fcr sie. Man gibt Familien mit Kindern keine Wohnung. Darum wird auch f\u00fcr dieses Kind kein Platz sein. Es ist unerw\u00fcnscht!\u201c\r\nGanz ruhig antwortete Gabriel: \u201eEben gerade darum soll es ein Kind sein, ein unerw\u00fcnschtes neben unerw\u00fcnschten. Der Mann seiner Mutter wird sie verlassen wollen. Der Machthaber der Zeit wird ihm nach dem Leben trachten. Sp\u00e4ter wird man nach ihm greifen wollen, weil es als Erwachsener anders denkt und lebt, als die anderen. Immer wird es unerw\u00fcnscht sein, so wie Gott selbst in der Welt unerw\u00fcnscht ist. Dieses Kind teilt das Schicksal mit Gott und mit allen ungeliebten Kindern und Menschen.\u201c<br>\r\nDa fragen erlaubt war, nahte sich einer jener Gruppe, die die Irdischen mit Schrecken ersch\u00fcttern wollten, und fragte: \u201eWarum soll es wieder einer von ihrer Art sein?\u201c<br>\r\nGabriels antworte: \u201eAlles Menschliche, das mehr ist als ein Mensch, wird ein \u00dcbermensch und unmenschlich. Sie haben unter den \u00dcbermenschen genug zu leiden. Gott gen\u00fcgt es, wenn sie Menschen sind. Du brauchst keine Angst zu haben. Das Kind wird von ihrer Art sein, aber nicht von ihrer Unart. Es wird ihnen zeigen, wie menschenfreundlich Gott ist, und wie gottesfreundlich der Mensch sein kann.\u201c<br>\r\nDarauf wagte kaum einer, etwas zu fragen, bis sich zuletzt einer bescheiden erkundigte: \u201ein welchem Land soll das Kind geboren werden, und ist es auch sicher, dass man es dort annimmt?\u201c<br>\r\nIhm antwortete Gabriel: \u201eEs wird in einem Volk geboren, das kein Volk ist und das keine Grenzen hat. Was dort geschieht, geh\u00f6rt von Anfang an der ganzen Welt. Und ob sie es annehmen? \u2013 Es ist eine Gabe Gottes und nicht ein Zwang. Es ist ein Angebot an alle.\u201c<br>\r\nWerner Reiser<\/p><p>\r\n<em><strong>3. Impuls<\/strong><\/em><br>\r\nGott ist nicht nur den gro\u00dfen und gewaltigen Dingen. Meist ist Gott in den ganz kleinen Dingen zu finden: in einem L\u00e4cheln, in einer gelingenden Begegnung, in einem Augenblick, in dem ich ganz bei mir bin. So ist Gott als Kind, ganz klein zur Welt gekommen. Wenn wir aufmerksam sind, dann k\u00f6nnen wir GOTT auch in unserem Schulalltag finden.<br>\r\nLass uns eine Woche auf die Spuren GOTTES in unserer Schule achten und uns darauf aufmerksam machen.<br><br>\r\nAchten wir darauf:<br>\r\n<ul>\r\n\t<li> \u2026 das Morgengebet in den Klassen und Kursen nicht zu vergessen. Vielleicht habt Ihr ja letzte Woche die ersten Minuten des Tages eine Musik geh\u00f6rt und wollt das fortf\u00fchren.<\/li>\r\n\r\n\t<li> \u2026 die kleinen, sch\u00f6nen Dinge wahrzunehmen.<br><\/li>\r\n\r\n\t<li> \u2026 GOTT bewusst DANKE zu sagen f\u00fcr die sch\u00f6nen Augenblicke, die ich erlebe.<\/li>\r\n<br><\/p><p><\/ul>\r\n\r\n\r\n<em><strong>4. Gebet<\/strong><\/em><br>\r\nHerr,\r\nmanchmal will ich das Gro\u00dfe, das Riesige,\r\nimmer nur noch mehr!\r\nAber manchmal ist es eher wie Weihnachten.\r\nDa wurdest Du, gro\u00dfer Gott, ganz klein geboren!\r\nDas war dein Plan.\r\nDu liebst die kleinen Dinge und Menschen,\r\ndie kleinen Begebenheiten.\r\nSo machst du dich heute noch klein, damit wir dich fassen k\u00f6nnen.\r\nLehre mich, das kleine zu sch\u00e4tzen und darin die gr\u00f6\u00dfte Freude zu finden.\r\nDanke, dass du mich nicht &#8222;riesig erschreckst&#8220;,\r\nsondern mich &#8222;klitzeklein&#8220; abholst wo ich stehe!\r\nDu bist ein guter, liebevoller Gott!\r\nAmen\r\n(nach einer unbekannten Quelle)","protected":false},"excerpt":{"rendered":"19. Dezember 2016. 1. Lied 2. Geschichte Der Himmel war ratlos. Keiner der Himmlischen wusste mehr, wie man den Menschen beikommen k\u00f6nnte. Die Irdischen waren f\u00fcr die Geheimnisse des Himmels taub und blind geworden. Die Tr\u00e4ume waren erloschen. Dieser \u00f6de Zustand durfte nicht um sich greifen. So blieb den Himmlischen nichts anderes \u00fcbrig, als \u00fcber m\u00f6gliche Wege miteinander zu verhandeln. Eine Gruppe wies darauf hin, dass fr\u00fcher gro\u00dfe Naturkatastrophen die irdischen am ehesten nachdenklich gestimmt h\u00e4tten. Doch dagegen wurde einhellig Einspruch erhoben: \u201eStrafaktionen k\u00f6nnen doch nicht himmlische Mittel sein!\u201c Da w\u00e4re es doch sinnvoller, meinte eine andere Gruppe, in voller Ausr\u00fcstung den Irdischen gegen\u00fcberzutreten und sie mit Glanz und Gloria zu \u00fcberw\u00e4ltigen, dass keiner mehr die Augen verschlie\u00dfen k\u00f6nne. Aber die J\u00fcngeren waren solchen Machtdemonstrationen gegen\u00fcber v\u00f6llig abgeneigt: \u201eWir werden wohl im Moment Eindruck machen, aber wenn sie uns nicht mehr sehen, bleiben ihnen nur unsere himmlischen Heere in Erinnerung, und sie werden nicht z\u00f6gern, unseren Auftritt nachzuahmen und selber Heere aufzustellen.\u201c Bisher hatte sich eine weitere Gruppe zur\u00fcckgehalten. Doch ihren Mienen war abzulesen, dass sie mit keinem Vorschlag einverstanden waren. \u201eWir seit Wochen den irdischen Markt erforscht. Man muss wissen, was sie erwarten und welche Bed\u00fcrfnisse sie haben. Danach m\u00fcssen wir unsere Absichten richten, sonst bleibt es ein Angebot ohne Nachfrage.\u201c Pl\u00f6tzlich wurde es still. Gabriel war zu ihnen getreten. Er war bei IHM gewesen. Nun stand er unter ihnen und strahlte sie an. Dann sagte er: \u201eEin Kind!\u201c Und als ihn alle sprachlos anstarrten, wiederholte er: \u201eEin Kind. Er gibt ihnen ein Kind. Das ist Seine Antwort auf die Entfremdung der Menschen.\u201c \u201eEin Kind? Ein Kind!\u201c, riefen alle durcheinander, und es klang staunend und erschrocken, bewundernd und abwehrend zugleich. Ein Kind \u2013 wie g\u00f6ttlich, wie gew\u00f6hnlich, wie einfach, wie unverst\u00e4ndlich! Als erstes brach es aus jenen heraus, die die Irdischen erforscht hatten: \u201eAber sie wollen das Kind doch nicht. Sie wollen \u00fcberhaupt keine Kinder mehr. Kinder sind unerw\u00fcnscht! Sie haben keinen Platz f\u00fcr sie. Man gibt Familien mit Kindern keine Wohnung. Darum wird auch f\u00fcr dieses Kind kein Platz sein. Es ist unerw\u00fcnscht!\u201c Ganz ruhig antwortete Gabriel: \u201eEben gerade darum soll es ein Kind sein, ein unerw\u00fcnschtes neben unerw\u00fcnschten. Der Mann seiner Mutter wird sie verlassen wollen. Der Machthaber der Zeit wird ihm nach dem Leben trachten. Sp\u00e4ter wird man nach ihm greifen wollen, weil es als Erwachsener anders denkt und lebt, als die anderen. Immer wird es unerw\u00fcnscht sein, so wie Gott selbst in der Welt unerw\u00fcnscht ist. Dieses Kind teilt das Schicksal mit Gott und mit allen ungeliebten Kindern und Menschen.\u201c Da fragen erlaubt war, nahte sich einer jener Gruppe, die die Irdischen mit Schrecken ersch\u00fcttern wollten, und fragte: \u201eWarum soll es wieder einer von ihrer Art sein?\u201c Gabriels antworte: \u201eAlles Menschliche, das mehr ist als ein Mensch, wird ein \u00dcbermensch und unmenschlich. Sie haben unter den \u00dcbermenschen genug zu leiden. Gott gen\u00fcgt es, wenn sie Menschen sind. Du brauchst keine Angst zu haben. Das Kind wird von ihrer Art sein, aber nicht von ihrer Unart. Es wird ihnen zeigen, wie menschenfreundlich Gott ist, und wie gottesfreundlich der Mensch sein kann.\u201c Darauf wagte kaum einer, etwas zu fragen, bis sich zuletzt einer bescheiden erkundigte: \u201ein welchem Land soll das Kind geboren werden, und ist es auch sicher, dass man es dort annimmt?\u201c Ihm antwortete Gabriel: \u201eEs wird in einem Volk geboren, das kein Volk ist und das keine Grenzen hat. Was dort geschieht, geh\u00f6rt von Anfang an der ganzen Welt. Und ob sie es annehmen? \u2013 Es ist eine Gabe Gottes und nicht ein Zwang. Es ist ein Angebot an alle.\u201c Werner Reiser 3. Impuls Gott ist nicht nur den gro\u00dfen und gewaltigen Dingen. Meist ist Gott in den ganz kleinen Dingen zu finden: in einem L\u00e4cheln, in einer gelingenden Begegnung, in einem Augenblick, in dem ich ganz bei mir bin. So ist Gott als Kind, ganz klein zur Welt gekommen. Wenn wir aufmerksam sind, dann k\u00f6nnen wir GOTT auch in unserem Schulalltag finden. Lass uns eine Woche auf die Spuren GOTTES in unserer Schule achten und uns darauf aufmerksam machen. Achten wir darauf: \u2026 das Morgengebet in den Klassen und Kursen nicht zu vergessen. Vielleicht habt Ihr ja letzte Woche die ersten Minuten des Tages eine Musik geh\u00f6rt und wollt das fortf\u00fchren. \u2026 die kleinen, sch\u00f6nen Dinge wahrzunehmen. \u2026 GOTT bewusst DANKE zu sagen f\u00fcr die sch\u00f6nen Augenblicke, die ich erlebe. 4. Gebet Herr, manchmal will ich das Gro\u00dfe, das Riesige, immer nur noch mehr! Aber manchmal ist es eher wie Weihnachten. Da wurdest Du, gro\u00dfer Gott, ganz klein geboren! Das war dein Plan. Du liebst die kleinen Dinge und Menschen, die kleinen Begebenheiten. So machst du dich heute noch klein, damit wir dich fassen k\u00f6nnen. Lehre mich, das kleine zu sch\u00e4tzen und darin die gr\u00f6\u00dfte Freude zu finden. Danke, dass du mich nicht &#8222;riesig erschreckst&#8220;, sondern mich &#8222;klitzeklein&#8220; abholst wo ich stehe! Du bist ein guter, liebevoller Gott! Amen (nach einer unbekannten Quelle)","protected":false},"author":3,"featured_media":10713,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:32:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/10712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=10712"}],"version-history":[{"count":3,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/10712\/revisions"}],"predecessor-version":[{"id":10716,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/10712\/revisions\/10716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/10713"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=10712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=10712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=10712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}