{"id":12907,"date":"2017-06-29T12:22:27","date_gmt":"2017-06-29T10:22:27","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=12907"},"modified":"2017-06-29T20:42:53","modified_gmt":"2017-06-29T18:42:53","slug":"patenseminar-2017","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/patenseminar-2017\/","title":{"rendered":"Patenseminar 2017"},"content":{"rendered":"<a attid=\"12909\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2017\/06\/2017_06Patenseminar05.jpg\" data-rel=fancybox rel=\"lightbox[12907]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2017\/06\/2017_06Patenseminar05-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"alignright size-medium wp-image-12909\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2017\/06\/2017_06Patenseminar05-300x200.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2017\/06\/2017_06Patenseminar05-768x512.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2017\/06\/2017_06Patenseminar05-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Die neuen Patinnen und Paten waren ausgew\u00e4hlt. Sie wurden begr\u00fc\u00dft. Jetzt wurde es Zeit, sie in die Arbeit einzuf\u00fchren und ihnen das erste Handwerkszeug mitzugeben. J\u00e4hrlich geschieht dies beim Patenseminar, das vom \u201eFranziskanischen Bildungswerk\u201c organisiert wird und in diesem Jahr vom 12. bis 14. Juni 2017 in Herbstein stattfand. Es wird von den verantwortlichen \u201ePateneltern\u201c vorbereitet und den \u201ealten Paten\u201c inhaltlich unterst\u00fctzt. Darin liegt die St\u00e4rke der Patenarbeit, dass die erfahrenen Sch\u00fclerinnen und Sch\u00fcler den Neuen viele Informationen weitergeben k\u00f6nnen. Das geschah in einem Info-Parcours oder bei Rollenspielen, die typische Situationen der Patenarbeit aufgriffen. Ein gro\u00dfes Kooperationsspiel f\u00fcllte fast den ganzen Nachmittag des zweiten Tages aus. Nat\u00fcrlich kamen Zeiten der Erholung, des Gespr\u00e4ches mit und ohne Stockbrot nicht zu kurz. Zuletzt wurde das kommende Jahr geplant und damit kann es f\u00fcr die sog. \u201eK\u00fcken\u201c gut losgehen.\r\n\r\nWeitere Fotos vom Seminar <a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/galerie\/nggallery\/allgemeines_album\/Patenseminar-2017\">hier.<\/a>","protected":false},"excerpt":{"rendered":"Die neuen Patinnen und Paten waren ausgew\u00e4hlt. Sie wurden begr\u00fc\u00dft. Jetzt wurde es Zeit, sie in die Arbeit einzuf\u00fchren und ihnen das erste Handwerkszeug mitzugeben. J\u00e4hrlich geschieht dies beim Patenseminar, das vom \u201eFranziskanischen Bildungswerk\u201c organisiert wird und in diesem Jahr vom 12. bis 14. Juni 2017 in Herbstein stattfand. Es wird von den verantwortlichen \u201ePateneltern\u201c vorbereitet und den \u201ealten Paten\u201c inhaltlich unterst\u00fctzt. Darin liegt die St\u00e4rke der Patenarbeit, dass die erfahrenen Sch\u00fclerinnen und Sch\u00fcler den Neuen viele Informationen weitergeben k\u00f6nnen. Das geschah in einem Info-Parcours oder bei Rollenspielen, die typische Situationen der Patenarbeit aufgriffen. Ein gro\u00dfes Kooperationsspiel f\u00fcllte fast den ganzen Nachmittag des zweiten Tages aus. Nat\u00fcrlich kamen Zeiten der Erholung, des Gespr\u00e4ches mit und ohne Stockbrot nicht zu kurz. Zuletzt wurde das kommende Jahr geplant und damit kann es f\u00fcr die sog. \u201eK\u00fcken\u201c gut losgehen. Weitere Fotos vom Seminar hier.","protected":false},"author":3,"featured_media":12908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[81],"class_list":["post-12907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-paten"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:09:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/12907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=12907"}],"version-history":[{"count":4,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/12907\/revisions"}],"predecessor-version":[{"id":12977,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/12907\/revisions\/12977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/12908"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=12907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=12907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=12907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}