{"id":1400,"date":"2013-11-25T18:47:33","date_gmt":"2013-11-25T17:47:33","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=1400"},"modified":"2014-01-03T18:40:06","modified_gmt":"2014-01-03T17:40:06","slug":"feuchtfroehlich-und-bewegend-franziskustag","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/feuchtfroehlich-und-bewegend-franziskustag\/","title":{"rendered":"Feuchtfr\u00f6hlich und beWEGend &#8211; Franziskustag"},"content":{"rendered":"<p><a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2013\/11\/Franziskustaglogo2.jpg\" rel=\"lightbox[1400]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1433\" alt=\"Franziskustaglogo2\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2013\/11\/Franziskustaglogo2-300x201.jpg\" width=\"300\" height=\"201\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2013\/11\/Franziskustaglogo2-300x201.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2013\/11\/Franziskustaglogo2.jpg 510w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Petrus meinte es \u2013 verstehe, wer will \u2013 nicht gut mit uns am vorletzten Tag vor den Herbstferien: Der f\u00fcr unseren lange geplanten Sponsorenlauf erhoffte \u201eSegen von oben\u201c fiel reichlich feucht aus\u2026 Aber kurzfristige \u00c4nderungen schufen einen vern\u00fcnftigen Rahmen, der es doch noch allen Sch\u00fclern erm\u00f6glichte, ihre bereits zugesagten Spendengelder zu erlaufen, indem jede Klasse eine 2,5km- Runde durch den Wald \u201edrehte\u201c. So wurde der Sportdress oder das T-Shirt in Klassenfarbe gegen wasserresistente Bekleidung eingetauscht und bunt leuchteten die Regenschirme im tr\u00fcb-herbstlichen Niederwald\u2026<\/p>\r\n<p>Wer sich die <a href=\"\/cms\/galerie\/nggallery\/fotos\/franziskustag-am-10-oktober-2013\/\">Bilder in der Galerie<\/a> anschaut, sieht: Der Stimmung tat das keinen Abbruch! Der Er\u00f6ffnungslauf ging sogar wie geplant vonstatten: Herr Wolf und Frau D\u00e4hn joggten durch den Regen und \u00fcberraschte Sch\u00fclerscharen wurden im Laufe des Morgens immer wieder von einem nimmerm\u00fcden tropfnassen Schulleiter \u00fcberrundet, dem die Kurzstrecke offensichtlich nicht mal als Aufw\u00e4rmtraining gen\u00fcgte und der noch dazu in einer Spontanaktion Umleitungshinweise anbrachte, da geplante Wegstrecken \u00fcberflutet waren. Toller Einsatz, den auch so mancher Sch\u00fcler anerkennend honorierte (\u201eDass der so was macht, finde ich ja gut!\u201c). Und auch toll, dass die nur sehr vereinzelt murrenden Sch\u00fclerInnen so mitzogen! Denn dass wir den widrigen Bedingungen trotzten und den Lauf nicht cancelten, hat sich wahrlich ausgezahlt: Schon jetzt &#8211; die Sponsorenbetr\u00e4ge gehen derzeit noch ein &#8211; steht fest, dass unser Einsatz mindestens 15.000 \u20ac einbrachte, die wir der Manoel-Monteiro-Schule \u00fcberweisen k\u00f6nnen!<\/p>\r\n<p>Absolut trockene F\u00fc\u00dfe behielten wir bei dem Rahmenprogramm des Laufs, dem Er\u00f6ffnungs-Gottesdienst und dem Abschlussfest \u201enach getaner Arbeit\u201c in der Aula. \u201eBewegend und bewegt\u201c \u2013 so setzte sich unser Tagesmotto auch hier fort: Es war <strong>bewegend<\/strong>,<\/p>\r\n<ul>\r\n<li>als Bruder Michael zu Beginn des Gottesdienstes nach 7 Jahren als \u201ealter-neuer\u201c Schulseelsorger von seinem evangelischen Kollegen Wolfgang Bromme begr\u00fc\u00dft wurde und sich selbst an der Kreuzburg in gewohnt locker-liebenswerter Weise \u201ezur\u00fcckmeldete\u201c.<\/li>\r\n<li>dass Br. Stefan, der den Franziskustag noch mit vorbereitet hatte, eigens aus Hofheim anreiste, um das Ergebnis eifriger und aufw\u00e4ndiger Vorplanungen miterleben zu k\u00f6nnen. &#8211; als Melanie Krause Pereira (8c), portugiesisch sprechendes Mitglied der Eine-Welt-Gruppe (und einzige Sch\u00fclerin in dieser Gruppe!) \u00fcber ihre Beziehung zu Brasilien sprach &#8211; und ihr Mitsch\u00fcler Manuel Br\u00f6ckers \u00fcber Capoeira und seine Freundschaft mit Stefano aus Brasilien.<\/li>\r\n<li>als unsere Sekret\u00e4rin Frau Tourlonias und Frau Br\u00f6ckers von ber\u00fchrenden Begegnungen und Erlebnissen in Brasilien erz\u00e4hlten. &#8211; als Bruder Bernardin in gewohnt erfrischender Begeisterung und anhand von Bildern schilderte, was durch Engagement hier dort in Bacabal an der Manoel-Monteiro-Schule schon alles bewegt wurde.<\/li>\r\n<li>als \u2013 dem Technik-Team und Br. Bernardin sei Dank! \u2013 die Gru\u00dfbotschaft aus Bacabal \u00fcber die Leinwand flimmerte und uns zus\u00e4tzlich zum \u201eRegenlauf\u201c motivierte, weil uns klar wurde: Der Einsatz lohnt!<\/li>\r\n<li>als Herr Wolf und B\u00fcrgermeister Friedhelm Engel Anerkennung und gute W\u00fcnsche f\u00fcr den Tag mit auf den Weg gaben und den Startschuss f\u00fcr den Sponsorenlauf setzten.<\/li>\r\n<li>als uns bewusst wurde, dass \u201eFlinke H\u00e4nde, flinke F\u00fc\u00dfe\u201c nicht nur gesungen, sondern auch gelebt wurde an diesem Tag: Viele flinke, wohl meistens m\u00fctterliche H\u00e4nde zauberten ein riesiges, wunderbares Buffet<\/li>\r\n<li>viele flinke F\u00fc\u00dfe und kleine Schritte durch den Niederwald in Gro\u00dfkrotzenburg schaffen es, dort, in Brasilien, einiges zu ver\u00e4ndern\u2026<\/li>\r\n<li>dass so viele Sch\u00fclerInnen die geschilderte Bedeutung des Tucumringes (Solidarit\u00e4t mit den Armen und Symbol f\u00fcr die eigenen Kraftquellen, aus denen ich auf \u201eDurststrecken meines Lebens\u201c sch\u00f6pfen kann) offensichtlich so ber\u00fchrte, dass sie ihn scharenweise schon w\u00e4hrend und auch nach der Abschlussveranstaltung erwarben.<\/li>\r\n<li>als Magdalena Kanthak, ehemalige Kreuzburg-Sch\u00fclerin und vor einigen Jahren Praktikantin in unserem Brasilienprojekt in Bacabal, uns lebhaft etwas von ihren Erlebnissen in der brasilianischen Schule erz\u00e4hlte \u2013 und als unsere Sch\u00fclerInnen sehr aufmerksam zuh\u00f6rten und interessiert nachfragten!<\/li>\r\n<li>dass die Sambakl\u00e4nge sogar spontane \u201eTanzwutanf\u00e4lle\u201c bei Sch\u00fclern und Lehrern ausl\u00f6sten &#8211; f\u00fcr mich DAS Bild des Tages: der gl\u00fcckselig l\u00e4chelnd-tanzende und die Brasilienflagge \u201eOrdem e Progresso\u201c schwenkende Bruder Bernardin inmitten von Kolleginnen und Sch\u00fclern auf der Aulab\u00fchne!<\/li>\r\n<\/ul>\r\n<p>Damit erf\u00fcllte sich, neben den bereits erfolgten Waldl\u00e4ufen, auch der zweite Teil unseres Mottos : beWEGt haben sich n\u00e4mlich viele:<\/p>\r\n<ul>\r\n<li>Die flinken Finger von Herrn Heindel auf den Klaviertasten\u2026<\/li>\r\n<li>Die Sch\u00fclerInnen der Tanz-AG von Frau Stickelmayer, der Jazztanz-AG von Frau Grimm und aus der 8c mit ihren mitrei\u00dfend-sch\u00f6nen Tanzdarbietungen.<\/li>\r\n<li>Die Capoeira-AG der Schule mit ihrem AG-Leiter Fabricio du Vinage, die rhythmisch bewegt echtes Brasilien-Feeling erzeugte.<\/li>\r\n<li>Bei der von Frau Fuest und Frau Cibis kreativ und mit viel Liebe zum Detail vorbereiteten Brasilien-Rallye f\u00fcr die Klassen 5-7.<\/li>\r\n<li>Frau Stickelmayer-Buchheim, die unerm\u00fcdlich im Rahmen der Brasilien-Rallye Sambakurse abhielt und es schaffte, fr\u00f6hliche Sambastimmung in die Aula und viele flinke F\u00fc\u00dfe \u201ein motion\u201c zu bringen!<\/li>\r\n<li>Die Unterst\u00fctzer aus der Elternschaft, die unter der routinierten Organisation von Frau Wallpott die Buffetbeitr\u00e4ge zauberten (schon optisch ein Genuss!) und tats\u00e4chlich fast bis auf den letzten Kr\u00fcmel verkauften (Bewegung macht hungrig! ) oder spontan auf Hilferufe reagierten, als noch ein Fu\u00dfballtor ben\u00f6tigt wurde.<\/li>\r\n<li>Schon viele Monate im Voraus das Planungsteam des Franziskustages (Br. Stefan, Fr. Cibis, Fr. Fuest, Hr. Jacob, Fr. Michaelis, Fr. Weiser, Fr. Br\u00f6ckers), dem es Anliegen und (manchmal schwei\u00dftreibender) Ansporn zugleich war, den ersten die gesamte Sek. I mobilisierenden Sponsorenlauf in der \u201eGeschichte der Kreuzburg\u201c auf die Beine bzw. flinken F\u00fc\u00dfe zu stellen!<\/li>\r\n<\/ul>\r\n<p>Allen Aktiven, auf und hinter der B\u00fchne, als L\u00e4ufer oder Unterst\u00fctzer sei ganz ganz herzlich gedankt.<\/p>\r\n<p>Die M\u00fchen haben sich gelohnt: Es war ein bewegt-bewegendes Event in einer guten Mixtur aus motions und emotions! Auf ein n\u00e4chstes Mal\u2026in zwei Jahren!<\/p>","protected":false},"excerpt":{"rendered":"Petrus meinte es \u2013 verstehe, wer will \u2013 nicht gut mit uns am vorletzten Tag vor den Herbstferien: Der f\u00fcr unseren lange geplanten Sponsorenlauf erhoffte \u201eSegen von oben\u201c fiel reichlich feucht aus\u2026 Aber kurzfristige \u00c4nderungen schufen einen vern\u00fcnftigen Rahmen, der es doch noch allen Sch\u00fclern erm\u00f6glichte, ihre bereits zugesagten Spendengelder zu erlaufen, indem jede Klasse eine 2,5km- Runde durch den Wald \u201edrehte\u201c. So wurde der Sportdress oder das T-Shirt in Klassenfarbe gegen wasserresistente Bekleidung eingetauscht und bunt leuchteten die Regenschirme im tr\u00fcb-herbstlichen Niederwald\u2026 Wer sich die Bilder in der Galerie anschaut, sieht: Der Stimmung tat das keinen Abbruch! Der Er\u00f6ffnungslauf ging sogar wie geplant vonstatten: Herr Wolf und Frau D\u00e4hn joggten durch den Regen und \u00fcberraschte Sch\u00fclerscharen wurden im Laufe des Morgens immer wieder von einem nimmerm\u00fcden tropfnassen Schulleiter \u00fcberrundet, dem die Kurzstrecke offensichtlich nicht mal als Aufw\u00e4rmtraining gen\u00fcgte und der noch dazu in einer Spontanaktion Umleitungshinweise anbrachte, da geplante Wegstrecken \u00fcberflutet waren. Toller Einsatz, den auch so mancher Sch\u00fcler anerkennend honorierte (\u201eDass der so was macht, finde ich ja gut!\u201c). Und auch toll, dass die nur sehr vereinzelt murrenden Sch\u00fclerInnen so mitzogen! Denn dass wir den widrigen Bedingungen trotzten und den Lauf nicht cancelten, hat sich wahrlich ausgezahlt: Schon jetzt &#8211; die Sponsorenbetr\u00e4ge gehen derzeit noch ein &#8211; steht fest, dass unser Einsatz mindestens 15.000 \u20ac einbrachte, die wir der Manoel-Monteiro-Schule \u00fcberweisen k\u00f6nnen! Absolut trockene F\u00fc\u00dfe behielten wir bei dem Rahmenprogramm des Laufs, dem Er\u00f6ffnungs-Gottesdienst und dem Abschlussfest \u201enach getaner Arbeit\u201c in der Aula. \u201eBewegend und bewegt\u201c \u2013 so setzte sich unser Tagesmotto auch hier fort: Es war bewegend, als Bruder Michael zu Beginn des Gottesdienstes nach 7 Jahren als \u201ealter-neuer\u201c Schulseelsorger von seinem evangelischen Kollegen Wolfgang Bromme begr\u00fc\u00dft wurde und sich selbst an der Kreuzburg in gewohnt locker-liebenswerter Weise \u201ezur\u00fcckmeldete\u201c. dass Br. Stefan, der den Franziskustag noch mit vorbereitet hatte, eigens aus Hofheim anreiste, um das Ergebnis eifriger und aufw\u00e4ndiger Vorplanungen miterleben zu k\u00f6nnen. &#8211; als Melanie Krause Pereira (8c), portugiesisch sprechendes Mitglied der Eine-Welt-Gruppe (und einzige Sch\u00fclerin in dieser Gruppe!) \u00fcber ihre Beziehung zu Brasilien sprach &#8211; und ihr Mitsch\u00fcler Manuel Br\u00f6ckers \u00fcber Capoeira und seine Freundschaft mit Stefano aus Brasilien. als unsere Sekret\u00e4rin Frau Tourlonias und Frau Br\u00f6ckers von ber\u00fchrenden Begegnungen und Erlebnissen in Brasilien erz\u00e4hlten. &#8211; als Bruder Bernardin in gewohnt erfrischender Begeisterung und anhand von Bildern schilderte, was durch Engagement hier dort in Bacabal an der Manoel-Monteiro-Schule schon alles bewegt wurde. als \u2013 dem Technik-Team und Br. Bernardin sei Dank! \u2013 die Gru\u00dfbotschaft aus Bacabal \u00fcber die Leinwand flimmerte und uns zus\u00e4tzlich zum \u201eRegenlauf\u201c motivierte, weil uns klar wurde: Der Einsatz lohnt! als Herr Wolf und B\u00fcrgermeister Friedhelm Engel Anerkennung und gute W\u00fcnsche f\u00fcr den Tag mit auf den Weg gaben und den Startschuss f\u00fcr den Sponsorenlauf setzten. als uns bewusst wurde, dass \u201eFlinke H\u00e4nde, flinke F\u00fc\u00dfe\u201c nicht nur gesungen, sondern auch gelebt wurde an diesem Tag: Viele flinke, wohl meistens m\u00fctterliche H\u00e4nde zauberten ein riesiges, wunderbares Buffet viele flinke F\u00fc\u00dfe und kleine Schritte durch den Niederwald in Gro\u00dfkrotzenburg schaffen es, dort, in Brasilien, einiges zu ver\u00e4ndern\u2026 dass so viele Sch\u00fclerInnen die geschilderte Bedeutung des Tucumringes (Solidarit\u00e4t mit den Armen und Symbol f\u00fcr die eigenen Kraftquellen, aus denen ich auf \u201eDurststrecken meines Lebens\u201c sch\u00f6pfen kann) offensichtlich so ber\u00fchrte, dass sie ihn scharenweise schon w\u00e4hrend und auch nach der Abschlussveranstaltung erwarben. als Magdalena Kanthak, ehemalige Kreuzburg-Sch\u00fclerin und vor einigen Jahren Praktikantin in unserem Brasilienprojekt in Bacabal, uns lebhaft etwas von ihren Erlebnissen in der brasilianischen Schule erz\u00e4hlte \u2013 und als unsere Sch\u00fclerInnen sehr aufmerksam zuh\u00f6rten und interessiert nachfragten! dass die Sambakl\u00e4nge sogar spontane \u201eTanzwutanf\u00e4lle\u201c bei Sch\u00fclern und Lehrern ausl\u00f6sten &#8211; f\u00fcr mich DAS Bild des Tages: der gl\u00fcckselig l\u00e4chelnd-tanzende und die Brasilienflagge \u201eOrdem e Progresso\u201c schwenkende Bruder Bernardin inmitten von Kolleginnen und Sch\u00fclern auf der Aulab\u00fchne! Damit erf\u00fcllte sich, neben den bereits erfolgten Waldl\u00e4ufen, auch der zweite Teil unseres Mottos : beWEGt haben sich n\u00e4mlich viele: Die flinken Finger von Herrn Heindel auf den Klaviertasten\u2026 Die Sch\u00fclerInnen der Tanz-AG von Frau Stickelmayer, der Jazztanz-AG von Frau Grimm und aus der 8c mit ihren mitrei\u00dfend-sch\u00f6nen Tanzdarbietungen. Die Capoeira-AG der Schule mit ihrem AG-Leiter Fabricio du Vinage, die rhythmisch bewegt echtes Brasilien-Feeling erzeugte. Bei der von Frau Fuest und Frau Cibis kreativ und mit viel Liebe zum Detail vorbereiteten Brasilien-Rallye f\u00fcr die Klassen 5-7. Frau Stickelmayer-Buchheim, die unerm\u00fcdlich im Rahmen der Brasilien-Rallye Sambakurse abhielt und es schaffte, fr\u00f6hliche Sambastimmung in die Aula und viele flinke F\u00fc\u00dfe \u201ein motion\u201c zu bringen! Die Unterst\u00fctzer aus der Elternschaft, die unter der routinierten Organisation von Frau Wallpott die Buffetbeitr\u00e4ge zauberten (schon optisch ein Genuss!) und tats\u00e4chlich fast bis auf den letzten Kr\u00fcmel verkauften (Bewegung macht hungrig! ) oder spontan auf Hilferufe reagierten, als noch ein Fu\u00dfballtor ben\u00f6tigt wurde. Schon viele Monate im Voraus das Planungsteam des Franziskustages (Br. Stefan, Fr. Cibis, Fr. Fuest, Hr. Jacob, Fr. Michaelis, Fr. Weiser, Fr. Br\u00f6ckers), dem es Anliegen und (manchmal schwei\u00dftreibender) Ansporn zugleich war, den ersten die gesamte Sek. I mobilisierenden Sponsorenlauf in der \u201eGeschichte der Kreuzburg\u201c auf die Beine bzw. flinken F\u00fc\u00dfe zu stellen! Allen Aktiven, auf und hinter der B\u00fchne, als L\u00e4ufer oder Unterst\u00fctzer sei ganz ganz herzlich gedankt. Die M\u00fchen haben sich gelohnt: Es war ein bewegt-bewegendes Event in einer guten Mixtur aus motions und emotions! Auf ein n\u00e4chstes Mal\u2026in zwei Jahren!","protected":false},"author":3,"featured_media":1174,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[213,206],"class_list":["post-1400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-gottesdienst","tag-manuel-monteiro-schule"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:47:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/1400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=1400"}],"version-history":[{"count":3,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/1400\/revisions"}],"predecessor-version":[{"id":1434,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/1400\/revisions\/1434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/1174"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=1400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=1400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=1400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}