{"id":16361,"date":"2018-01-26T12:26:37","date_gmt":"2018-01-26T11:26:37","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=16361"},"modified":"2018-01-26T12:28:31","modified_gmt":"2018-01-26T11:28:31","slug":"miteinander-von-musik-und-farbe","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/miteinander-von-musik-und-farbe\/","title":{"rendered":"Miteinander von Musik und Farbe"},"content":{"rendered":"<a attid=\"16362\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth11.jpg\" rel=\"lightbox[16361]\"><img decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth11-1024x513.jpg\" alt=\"\" width=\"360\" class=\"alignright size-large wp-image-16362\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth11-1024x513.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth11-300x150.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth11-768x385.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth11.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p>Mit dem Lied \u201eMiteinander\u201c beginnt das Konzert der Band LAETITIA am Samstagabend und endet mit dem gleichen Song als Zugabe. W\u00e4hrend des Konzerts entsteht ein von der Musik und den Texten inspiriertes Gem\u00e4lde der K\u00fcnstlerin Anita J\u00e4ger. Die Zuschauer erleben eine Vielfalt an Sinneseindr\u00fccken: Sie h\u00f6ren die Musik, sie sehen, wie das Bild entsteht, sie sind aufgefordert, selbst mitzusingen und werden durch die Texte der Lieder angeregt zum Nachdenken.<\/p><p>\r\nDie christliche Liedermacherband LAETITIA spielt an diesem Abend Songs \u00fcber das Leben, \u00fcber Gott und die Kirche. Alle St\u00fccke wurden zusammen mit der K\u00fcnstlerin Anita J\u00e4ger ausgew\u00e4hlt. Es ist nicht das erste Mal, dass beide gemeinsam ein Malkonzert durchf\u00fchren. Im Jubil\u00e4umsjahr der Kreuzburg war es der Malerin wichtig, mit der Auff\u00fchrung eines solchen Konzertes einen Beitrag f\u00fcr ihre Schule, in der sie als Kunstp\u00e4dagogin arbeitet, zu leisten. <\/p><p>\r\n<a attid=\"16363\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth13.jpg\" rel=\"lightbox[16361]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth13-180x300.jpg\" alt=\"\" width=\"180\" height=\"300\" class=\"alignleft size-medium wp-image-16363\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth13-180x300.jpg 180w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth13-613x1024.jpg 613w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth13.jpg 718w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a>W\u00e4hrend die Besucher die Texte \u00fcber die Hetze des Alltags, die Macht des Internets oder die Rolle Gottes im Leben h\u00f6ren, sehen sie, wie sich nach und nach die Leinwand vor ihren Augen ver\u00e4ndert. Die K\u00fcnstlerin beginnt mit hellen Gelb- und Rott\u00f6nen. Mit vorbereiteten Schablonen klebt sie Teile des Bildes ab und mit neu hinzukommenden Farben in Blau- und T\u00fcrkist\u00f6nen erhalten die Zuschauer neue Eindr\u00fccke des entstehenden Bildes. Das Gem\u00e4lde erscheint so in verschiedenen Schichten, die laut der K\u00fcnstlerin auch gewollt sind und damit die Vielschichtigkeit des Lebens darstellen.  Als gegen Ende des Konzertes die Schablonen entfernt werden, wandelt sich die Darstellung v\u00f6llig. Fenster und Menschenfiguren werden erkennbar, und der Farbeindruck ist ein vollkommen anderer. Insgesamt bleibt das Kunstwerk abstrakt. Die K\u00fcnstlerin erkl\u00e4rt dazu, dass sich im Abstrakten Gef\u00fchle und Eindr\u00fccke am besten darstellen lassen.<\/p><p>\r\n<a attid=\"16364\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth51.jpg\" rel=\"lightbox[16361]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth51-300x183.jpg\" alt=\"\" width=\"300\" height=\"183\" class=\"alignright size-medium wp-image-16364\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth51-300x183.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth51-768x468.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth51-1024x625.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth51.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Die Spannung unter den G\u00e4sten steigt am Ende des Abends, als das Bild verlost werden soll. Der ehemalige Sch\u00fcler Jonas J\u00e4ger, der mit viel Charme und lockerer Konversation den Abend moderiert hat, f\u00fchrt die Verlosung mit Hilfe der \u201eGl\u00fccksfee\u201c Frau Andrea D\u00e4hn, durch. Die Gewinnerin zeigt sich \u00fcberw\u00e4ltigt und ist sich sicher, einen guten Platz f\u00fcr das helle, strahlende Gem\u00e4lde zu finden. Die Einnahmen aus dem Losverkauf gehen an die Eine-Welt-Gruppe der Schule, die damit diverse Projekte unterst\u00fctzt.<\/p><p>\r\nDer Abend der besonderen ART, endet mit der M\u00f6glichkeit, an einer F\u00fchrung durch die Ausstellung \u201eDURCHKREUZTE WEGE\u201c der K\u00fcnstlerin teilzunehmen. <\/p>\r\n<a attid=\"16365\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth62.jpg\" rel=\"lightbox[16361]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth62-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" class=\"alignleft size-medium wp-image-16365\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth62-300x199.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth62-768x509.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth62-1024x679.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2018\/01\/2018_01Malkonzerth62.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Weitere Fotos vom Abend in unserer <a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/galerie\/nggallery\/allgemeines_album\/Malkonzert-am-20.-Januar-2018\">Galerie.<\/a>","protected":false},"excerpt":{"rendered":"Mit dem Lied \u201eMiteinander\u201c beginnt das Konzert der Band LAETITIA am Samstagabend und endet mit dem gleichen Song als Zugabe. W\u00e4hrend des Konzerts entsteht ein von der Musik und den Texten inspiriertes Gem\u00e4lde der K\u00fcnstlerin Anita J\u00e4ger. Die Zuschauer erleben eine Vielfalt an Sinneseindr\u00fccken: Sie h\u00f6ren die Musik, sie sehen, wie das Bild entsteht, sie sind aufgefordert, selbst mitzusingen und werden durch die Texte der Lieder angeregt zum Nachdenken. Die christliche Liedermacherband LAETITIA spielt an diesem Abend Songs \u00fcber das Leben, \u00fcber Gott und die Kirche. Alle St\u00fccke wurden zusammen mit der K\u00fcnstlerin Anita J\u00e4ger ausgew\u00e4hlt. Es ist nicht das erste Mal, dass beide gemeinsam ein Malkonzert durchf\u00fchren. Im Jubil\u00e4umsjahr der Kreuzburg war es der Malerin wichtig, mit der Auff\u00fchrung eines solchen Konzertes einen Beitrag f\u00fcr ihre Schule, in der sie als Kunstp\u00e4dagogin arbeitet, zu leisten. W\u00e4hrend die Besucher die Texte \u00fcber die Hetze des Alltags, die Macht des Internets oder die Rolle Gottes im Leben h\u00f6ren, sehen sie, wie sich nach und nach die Leinwand vor ihren Augen ver\u00e4ndert. Die K\u00fcnstlerin beginnt mit hellen Gelb- und Rott\u00f6nen. Mit vorbereiteten Schablonen klebt sie Teile des Bildes ab und mit neu hinzukommenden Farben in Blau- und T\u00fcrkist\u00f6nen erhalten die Zuschauer neue Eindr\u00fccke des entstehenden Bildes. Das Gem\u00e4lde erscheint so in verschiedenen Schichten, die laut der K\u00fcnstlerin auch gewollt sind und damit die Vielschichtigkeit des Lebens darstellen. Als gegen Ende des Konzertes die Schablonen entfernt werden, wandelt sich die Darstellung v\u00f6llig. Fenster und Menschenfiguren werden erkennbar, und der Farbeindruck ist ein vollkommen anderer. Insgesamt bleibt das Kunstwerk abstrakt. Die K\u00fcnstlerin erkl\u00e4rt dazu, dass sich im Abstrakten Gef\u00fchle und Eindr\u00fccke am besten darstellen lassen. Die Spannung unter den G\u00e4sten steigt am Ende des Abends, als das Bild verlost werden soll. Der ehemalige Sch\u00fcler Jonas J\u00e4ger, der mit viel Charme und lockerer Konversation den Abend moderiert hat, f\u00fchrt die Verlosung mit Hilfe der \u201eGl\u00fccksfee\u201c Frau Andrea D\u00e4hn, durch. Die Gewinnerin zeigt sich \u00fcberw\u00e4ltigt und ist sich sicher, einen guten Platz f\u00fcr das helle, strahlende Gem\u00e4lde zu finden. Die Einnahmen aus dem Losverkauf gehen an die Eine-Welt-Gruppe der Schule, die damit diverse Projekte unterst\u00fctzt. Der Abend der besonderen ART, endet mit der M\u00f6glichkeit, an einer F\u00fchrung durch die Ausstellung \u201eDURCHKREUZTE WEGE\u201c der K\u00fcnstlerin teilzunehmen. Weitere Fotos vom Abend in unserer Galerie.","protected":false},"author":3,"featured_media":16362,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[252,317],"tags":[],"class_list":["post-16361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fachbereich-1","category-jubilaeum"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:50:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/16361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=16361"}],"version-history":[{"count":6,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/16361\/revisions"}],"predecessor-version":[{"id":16371,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/16361\/revisions\/16371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/16362"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=16361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=16361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=16361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}