{"id":27210,"date":"2020-08-14T20:33:31","date_gmt":"2020-08-14T18:33:31","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=27210"},"modified":"2020-08-14T20:33:31","modified_gmt":"2020-08-14T18:33:31","slug":"angebot-ags-im-neuen-schuljahr-start-der-ag-anmeldungen","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/angebot-ags-im-neuen-schuljahr-start-der-ag-anmeldungen\/","title":{"rendered":"Angebot AGs im neuen Schuljahr &#8211; Start der AG-Anmeldungen"},"content":{"rendered":"<p>Ab Montag, 17.08.2020, ist die Anmeldung f\u00fcr AGs im Schuljahr 2020-21 freigeschaltet. Auch in diesem Jahr bietet unsere Schule wieder ein breites Spektrum an Arbeitsgemeinschaften (AGs) an. Eine \u00dcbersicht und eine Kurzbeschreibung der jeweiligen AG befinden sich <a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/arbeitsgemeinschaften\/\">hier<\/a> und als Aushang in der Eingangshalle gegen\u00fcber den Vertretungspl\u00e4nen.<br>\r\nInteressierte Sch\u00fclerinnen und Sch\u00fcler k\u00f6nnen sich \u00fcber das Online-Programm, das <a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/ag-wahl\/\">hier <\/a>zu finden ist, bis Sonntag, 23.08.2020 (23:59 Uhr) anmelden.               <br>\r\nDas Online-Formular muss nach dem Ausf\u00fcllen und Abschicken zus\u00e4tzlich ausgedruckt, von den Eltern unterschrieben und im Wahlkasten vor dem Sekretariat abgegeben werden. Da die Zuteilung zu den AGs \u00fcber die Online-Wahl erfolgt, ist es nicht m\u00f6glich, auf dem Ausdruck per Hand \u00c4nderungen vorzunehmen. Das ausgedruckte Blatt gilt als offizielle Genehmigung der Eltern zum Besuch der jeweiligen AG und wird archiviert.<br>\r\nZum Ende der zweiten Schulwoche werden die AG-Einteilungen in der Eingangshalle ausgeh\u00e4ngt, so dass die Kurse in der dritten Woche (ab 31.08.2020) beginnen k\u00f6nnen.<\/p><p>\r\n\r\nEine AG wird jeweils f\u00fcr das gesamte Schuljahr gew\u00e4hlt. Sie muss regelm\u00e4\u00dfig besucht werden und Fehlzeiten m\u00fcssen zeitnah beim AG-Leiter entschuldigt werden. Austritte, die nicht innerhalb der ersten drei Wochen nach Beginn der AG stattfinden, m\u00fcssen schriftlich begr\u00fcndet und von Herrn Hartelt genehmigt werden. Die Kinder sollten regelm\u00e4\u00dfig auf die Vertretungspl\u00e4nen schauen, da eine Raum\u00e4nderung oder ein Ausfall einer AG dort angezeigt wird.<\/p><p>\r\n\r\nBei R\u00fcckfragen bitte an Herrn Hartelt (<a href=\"mailto:hartelt.tobias@fgk-lehrer.de\">hartelt.tobias@fgk-lehrer.de<\/a>) wenden.<\/p>\r\n","protected":false},"excerpt":{"rendered":"Ab Montag, 17.08.2020, ist die Anmeldung f\u00fcr AGs im Schuljahr 2020-21 freigeschaltet. Auch in diesem Jahr bietet unsere Schule wieder ein breites Spektrum an Arbeitsgemeinschaften (AGs) an. Eine \u00dcbersicht und eine Kurzbeschreibung der jeweiligen AG befinden sich hier und als Aushang in der Eingangshalle gegen\u00fcber den Vertretungspl\u00e4nen. Interessierte Sch\u00fclerinnen und Sch\u00fcler k\u00f6nnen sich \u00fcber das Online-Programm, das hier zu finden ist, bis Sonntag, 23.08.2020 (23:59 Uhr) anmelden. Das Online-Formular muss nach dem Ausf\u00fcllen und Abschicken zus\u00e4tzlich ausgedruckt, von den Eltern unterschrieben und im Wahlkasten vor dem Sekretariat abgegeben werden. Da die Zuteilung zu den AGs \u00fcber die Online-Wahl erfolgt, ist es nicht m\u00f6glich, auf dem Ausdruck per Hand \u00c4nderungen vorzunehmen. Das ausgedruckte Blatt gilt als offizielle Genehmigung der Eltern zum Besuch der jeweiligen AG und wird archiviert. Zum Ende der zweiten Schulwoche werden die AG-Einteilungen in der Eingangshalle ausgeh\u00e4ngt, so dass die Kurse in der dritten Woche (ab 31.08.2020) beginnen k\u00f6nnen. Eine AG wird jeweils f\u00fcr das gesamte Schuljahr gew\u00e4hlt. Sie muss regelm\u00e4\u00dfig besucht werden und Fehlzeiten m\u00fcssen zeitnah beim AG-Leiter entschuldigt werden. Austritte, die nicht innerhalb der ersten drei Wochen nach Beginn der AG stattfinden, m\u00fcssen schriftlich begr\u00fcndet und von Herrn Hartelt genehmigt werden. Die Kinder sollten regelm\u00e4\u00dfig auf die Vertretungspl\u00e4nen schauen, da eine Raum\u00e4nderung oder ein Ausfall einer AG dort angezeigt wird. Bei R\u00fcckfragen bitte an Herrn Hartelt (hartelt.tobias@fgk-lehrer.de) wenden.","protected":false},"author":3,"featured_media":3845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[229],"class_list":["post-27210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-arbeitsgemeinschaften"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:46:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/27210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=27210"}],"version-history":[{"count":3,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/27210\/revisions"}],"predecessor-version":[{"id":27215,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/27210\/revisions\/27215"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=27210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=27210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=27210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}