{"id":35331,"date":"2023-02-07T18:15:23","date_gmt":"2023-02-07T17:15:23","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=35331"},"modified":"2023-02-09T16:09:31","modified_gmt":"2023-02-09T15:09:31","slug":"mathematikwettbewerb-2023","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/mathematikwettbewerb-2023\/","title":{"rendered":"Mathematikwettbewerb 2023"},"content":{"rendered":"<a attid=\"35332\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/20230202_Mathewettbewerb.jpg\" rel=\"lightbox[35331]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/20230202_Mathewettbewerb-300x245.jpg\" alt=\"\" width=\"300\" height=\"245\" class=\"alignright size-medium wp-image-35332\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/20230202_Mathewettbewerb-300x245.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/20230202_Mathewettbewerb-1024x836.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/20230202_Mathewettbewerb-768x627.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/20230202_Mathewettbewerb.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p>\r\nAuch in diesem Jahr hat das Franziskanergymnasium am traditionellen Mathematikwettbewerb des Landes Hessen teilgenommen. Alle Lernenden der Jahrgangsstufe 8 wurden am 01. Dezember herausgefordert, ihr gesamtes mathematisches Wissen unter Beweis zu stellen. Am besten abgeschnitten haben Antonia T. und Nils R. aus der Klasse 8b mit jeweils 47 von 48 Punkten. Neben den beiden Lernenden aus der Klasse 8b sind auch Philipp K. und Mona R. aus der Klasse 8e sowie Raphael P. aus der Klasse 8c f\u00fcr ihre herausragenden Leistungen zu Schulsiegern gek\u00fcrt worden. Alle zusammen vertreten die Kreuzburg am 01. M\u00e4rz beim Kreisentscheid an der Hohen Landesschule in Hanau. In der 2. Runde des Mathematikwettbewerbs wird entschieden, wer den Main-Kinzig-Kreis im Landesfinale der besten Mathematiker Hessens vertritt.<\/p>\r\n","protected":false},"excerpt":{"rendered":"Auch in diesem Jahr hat das Franziskanergymnasium am traditionellen Mathematikwettbewerb des Landes Hessen teilgenommen. Alle Lernenden der Jahrgangsstufe 8 wurden am 01. Dezember herausgefordert, ihr gesamtes mathematisches Wissen unter Beweis zu stellen. Am besten abgeschnitten haben Antonia T. und Nils R. aus der Klasse 8b mit jeweils 47 von 48 Punkten. Neben den beiden Lernenden aus der Klasse 8b sind auch Philipp K. und Mona R. aus der Klasse 8e sowie Raphael P. aus der Klasse 8c f\u00fcr ihre herausragenden Leistungen zu Schulsiegern gek\u00fcrt worden. Alle zusammen vertreten die Kreuzburg am 01. M\u00e4rz beim Kreisentscheid an der Hohen Landesschule in Hanau. In der 2. Runde des Mathematikwettbewerbs wird entschieden, wer den Main-Kinzig-Kreis im Landesfinale der besten Mathematiker Hessens vertritt.","protected":false},"author":3,"featured_media":35332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,251],"tags":[440,455],"class_list":["post-35331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-fachbereich-3","tag-mathematik","tag-wettbewerb"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:41:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/35331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=35331"}],"version-history":[{"count":2,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/35331\/revisions"}],"predecessor-version":[{"id":35337,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/35331\/revisions\/35337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/35332"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=35331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=35331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=35331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}