{"id":35383,"date":"2023-02-14T08:26:27","date_gmt":"2023-02-14T07:26:27","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=35383"},"modified":"2023-02-14T08:26:27","modified_gmt":"2023-02-14T07:26:27","slug":"debatte-um-debatte-erkaempft","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/debatte-um-debatte-erkaempft\/","title":{"rendered":"Debatte um Debatte erk\u00e4mpft"},"content":{"rendered":"<a attid=\"35384\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/JugendDebattiert1.png\" rel=\"lightbox[35383]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/JugendDebattiert1.png\" alt=\"\" width=\"201\" height=\"164\" class=\"alignleft size-full wp-image-35384\" \/><\/a><p>\r\nAm vergangenen Donnerstag, den 09.02.23, debattierten unsere Schulsieger, Hannes S. und Annika M., im Regionalwettbewerb von \u201eJugend debattiert\u201c. Dabei setzten sie sich mit den Fragen auseinander, ob in Neubaugebieten nur noch Mehrfamilienh\u00e4user gebaut werden sollten und ob auch Privathaushalte zur Katastrophenvorsorge verpflichtet werden sollten. In den leidenschaftlichen Debatten \u00fcberzeugten Hannes und Annika so sehr, dass sie es ins Finale schafften. In der Finaldebatte wurde es dann noch einmal spannend und das Debattenthema, ob in Hanau ein durch Los besetzter Jugendrat eingef\u00fchrt werden soll, forderte alle Finalistinnen und Finalisten. <\/p><p>\r\nDie Platzierungen nach diesem Finale unterschieden sich lediglich durch einen Punkt, wodurch deutlich wurde, wie qualifiziert und engagiert die Finalteilnehmenden waren. <a attid=\"35385\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/2023_02JugendDebattiert.jpg\" rel=\"lightbox[35383]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/2023_02JugendDebattiert-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" class=\"alignright size-medium wp-image-35385\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/2023_02JugendDebattiert-300x225.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/2023_02JugendDebattiert-768x576.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2023\/02\/2023_02JugendDebattiert.jpg 780w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Am Ende k\u00f6nnen wir Hannes und Annika zu Platz 2 und Platz 3 begl\u00fcckw\u00fcnschen, was eine grandiose Leistung in Vertretung f\u00fcr unsere Schule ist. Die besondere Leistung besteht vor allem darin, dass unsere beiden Schulsieger in diesem Regionalwettbewerb so weit gekommen sind. <\/p><p>\r\nHannes wird am 16. M\u00e4rz zur Landesqualifikation nach Frankfurt fahren und dort gegen die besten Debattandinnen und Debattanden aus Hessen S\u00fcd und Hessen Nord antreten. Dabei w\u00fcnschen wir ihm alles Gute und einen k\u00fchlen Kopf. <\/p>\r\n","protected":false},"excerpt":{"rendered":"Am vergangenen Donnerstag, den 09.02.23, debattierten unsere Schulsieger, Hannes S. und Annika M., im Regionalwettbewerb von \u201eJugend debattiert\u201c. Dabei setzten sie sich mit den Fragen auseinander, ob in Neubaugebieten nur noch Mehrfamilienh\u00e4user gebaut werden sollten und ob auch Privathaushalte zur Katastrophenvorsorge verpflichtet werden sollten. In den leidenschaftlichen Debatten \u00fcberzeugten Hannes und Annika so sehr, dass sie es ins Finale schafften. In der Finaldebatte wurde es dann noch einmal spannend und das Debattenthema, ob in Hanau ein durch Los besetzter Jugendrat eingef\u00fchrt werden soll, forderte alle Finalistinnen und Finalisten. Die Platzierungen nach diesem Finale unterschieden sich lediglich durch einen Punkt, wodurch deutlich wurde, wie qualifiziert und engagiert die Finalteilnehmenden waren. Am Ende k\u00f6nnen wir Hannes und Annika zu Platz 2 und Platz 3 begl\u00fcckw\u00fcnschen, was eine grandiose Leistung in Vertretung f\u00fcr unsere Schule ist. Die besondere Leistung besteht vor allem darin, dass unsere beiden Schulsieger in diesem Regionalwettbewerb so weit gekommen sind. Hannes wird am 16. M\u00e4rz zur Landesqualifikation nach Frankfurt fahren und dort gegen die besten Debattandinnen und Debattanden aus Hessen S\u00fcd und Hessen Nord antreten. Dabei w\u00fcnschen wir ihm alles Gute und einen k\u00fchlen Kopf.","protected":false},"author":3,"featured_media":35387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[161],"class_list":["post-35383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-jugend-debattiert"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:22:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/35383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=35383"}],"version-history":[{"count":3,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/35383\/revisions"}],"predecessor-version":[{"id":35403,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/35383\/revisions\/35403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/35387"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=35383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=35383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=35383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}