{"id":3568,"date":"2014-07-30T12:16:05","date_gmt":"2014-07-30T10:16:05","guid":{"rendered":"http:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=3568"},"modified":"2016-02-17T13:38:26","modified_gmt":"2016-02-17T12:38:26","slug":"auszeichnungen-fuer-besondere-naturwissenschaftliche-leistungen","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/auszeichnungen-fuer-besondere-naturwissenschaftliche-leistungen\/","title":{"rendered":"Auszeichnungen f\u00fcr besondere naturwissenschaftliche Leistungen"},"content":{"rendered":"Sch\u00fcler, die K\u00e4nguruspr\u00fcnge machen, an einer Olympiade teilnehmen, Wale bauen, die Tennisb\u00e4lle beschleunigen oder an der Schule einen F\u00fchrerschein machen, all das gab es im vergangenen Schuljahr. Es handelte sich dabei um Wettbewerbe im naturwissenschaftlichen Bereich. Die Sch\u00fcler, die bei diesen Wettbewerben besondere Erfolge erzielt haben, wurden nun zum Schuljahresende in einer kleinen Feierstunde von ihren Lehrern und Schulleiter Thomas Wolf geehrt.\r\nAlle Klassen der Jahrgangsstufe 6 der Kreuzburg machten beim K\u00e4nguruwettbewerb mit. In ganz Deutschland nahmen fast 890.000 Sch\u00fcler der Jahrgangsstufen 5 bis 13 teil. Von 150 erreichbaren Punkten wurden durchschnittlich 50 erreicht. Fiona K. und Lukas G. erzielten mit 101,25 einen ersten Preis.\r\nBei dem Mathematikwettbewerb der Jahrgangsstufe 8 des Landes Hessen hatten Nina B. und Luca B. die besten Ergebnisse im Main-Kinzig-Kreis.\r\nAls dritter Mathematikwettbewerb wurde noch f\u00fcr alle Jahrgangsstufen die freiwillige Teilnahme bei der Mathematik-Olympiade angeboten. Schulsieger wurden hier Jasmin C. aus der Klasse 8 und Kevin K. aus der Klasse 6.\r\nMaikel D., Helene R. und Maja-Sophie W. aus der 7. Klasse stellten sich im Explore Science Wettbewerb der Aufgabe, einen Fisch zu bauen, der im Wasser untergeht und erst nach einem bestimmten Zeitraum wieder auftaucht.\r\nEinen \u201eTeilchenbeschleuniger\u201c bauten Jonathan B. und Robert K. f\u00fcr \u201eExciting Physics\u201c. Sie bauten eine Apparatur, die einen Tennisball in ein Ziel bef\u00f6rdert, das erst kurz vor dem Wettbewerbsbeginn bekannt gegeben wurde. Mit ihrem Ger\u00e4t erzielten sie den 2. Platz.\r\nAls Letztes wurden in der Feierstunde noch zehn Sch\u00fcler aus der Jahrgangsstufe 9 geehrt, die in den letzten zwei Schuljahren in jeweils sieben Teilpr\u00fcfungen ihre Kenntnisse am Computer nachgewiesen hatten. Ihnen wurde das Zertifikat der DLGI (Dienstleistungsgesellschaft f\u00fcr Informatik) \u201eEurop\u00e4ischer Computerf\u00fchrerschein\u201c \u00fcberreicht.\r\n\r\n<a href=\"http:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2014\/07\/2014_07ehrungen.jpg\" data-rel=\"fancybox\" rel=\"lightbox[3568]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-3569\" src=\"http:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2014\/07\/2014_07ehrungen-1024x682.jpg\" alt=\"2014_07ehrungen\" width=\"960\" height=\"639\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2014\/07\/2014_07ehrungen-1024x682.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2014\/07\/2014_07ehrungen-300x199.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2014\/07\/2014_07ehrungen.jpg 1400w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a>","protected":false},"excerpt":{"rendered":"Sch\u00fcler, die K\u00e4nguruspr\u00fcnge machen, an einer Olympiade teilnehmen, Wale bauen, die Tennisb\u00e4lle beschleunigen oder an der Schule einen F\u00fchrerschein machen, all das gab es im vergangenen Schuljahr. Es handelte sich dabei um Wettbewerbe im naturwissenschaftlichen Bereich. Die Sch\u00fcler, die bei diesen Wettbewerben besondere Erfolge erzielt haben, wurden nun zum Schuljahresende in einer kleinen Feierstunde von ihren Lehrern und Schulleiter Thomas Wolf geehrt. Alle Klassen der Jahrgangsstufe 6 der Kreuzburg machten beim K\u00e4nguruwettbewerb mit. In ganz Deutschland nahmen fast 890.000 Sch\u00fcler der Jahrgangsstufen 5 bis 13 teil. Von 150 erreichbaren Punkten wurden durchschnittlich 50 erreicht. Fiona K. und Lukas G. erzielten mit 101,25 einen ersten Preis. Bei dem Mathematikwettbewerb der Jahrgangsstufe 8 des Landes Hessen hatten Nina B. und Luca B. die besten Ergebnisse im Main-Kinzig-Kreis. Als dritter Mathematikwettbewerb wurde noch f\u00fcr alle Jahrgangsstufen die freiwillige Teilnahme bei der Mathematik-Olympiade angeboten. Schulsieger wurden hier Jasmin C. aus der Klasse 8 und Kevin K. aus der Klasse 6. Maikel D., Helene R. und Maja-Sophie W. aus der 7. Klasse stellten sich im Explore Science Wettbewerb der Aufgabe, einen Fisch zu bauen, der im Wasser untergeht und erst nach einem bestimmten Zeitraum wieder auftaucht. Einen \u201eTeilchenbeschleuniger\u201c bauten Jonathan B. und Robert K. f\u00fcr \u201eExciting Physics\u201c. Sie bauten eine Apparatur, die einen Tennisball in ein Ziel bef\u00f6rdert, das erst kurz vor dem Wettbewerbsbeginn bekannt gegeben wurde. Mit ihrem Ger\u00e4t erzielten sie den 2. Platz. Als Letztes wurden in der Feierstunde noch zehn Sch\u00fcler aus der Jahrgangsstufe 9 geehrt, die in den letzten zwei Schuljahren in jeweils sieben Teilpr\u00fcfungen ihre Kenntnisse am Computer nachgewiesen hatten. Ihnen wurde das Zertifikat der DLGI (Dienstleistungsgesellschaft f\u00fcr Informatik) \u201eEurop\u00e4ischer Computerf\u00fchrerschein\u201c \u00fcberreicht.","protected":false},"author":3,"featured_media":3569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,251],"tags":[],"class_list":["post-3568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-fachbereich-3"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:46:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/3568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=3568"}],"version-history":[{"count":3,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/3568\/revisions"}],"predecessor-version":[{"id":3572,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/3568\/revisions\/3572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/3569"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=3568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=3568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=3568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}