{"id":5088,"date":"2015-03-17T11:43:41","date_gmt":"2015-03-17T10:43:41","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=5088"},"modified":"2016-02-17T13:31:16","modified_gmt":"2016-02-17T12:31:16","slug":"menschsein-und-es-auch-beweisen","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/menschsein-und-es-auch-beweisen\/","title":{"rendered":"\u201eMenschsein und es auch beweisen\u201c"},"content":{"rendered":"<a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-10.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5088]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-5090\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-10-300x225.jpg\" alt=\"150311-Scheck\u00fcbergabe an Malteser-10\" width=\"207\" height=\"155\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-10-300x225.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-10-1024x768.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-10.jpg 1200w\" sizes=\"auto, (max-width: 207px) 100vw, 207px\" \/><\/a>Am Mittwoch, dem 11.3.2015, war Dr. Constantin von Brandenstein-Zeppelin, Pr\u00e4sident des Malteser Hilfsdienstes, Gast an unserer Schule. Anlass war die \u00dcbergabe einer Spende an den Kinderhospizdienst der Malteser.\r\n<a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-02.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5088]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-5093\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-02-300x225.jpg\" alt=\"150311-Scheck\u00fcbergabe an Malteser-02\" width=\"236\" height=\"177\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-02-300x225.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-02-1024x768.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-02.jpg 1200w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/><\/a>Der Kammerchor\u00a0 unter Leitung von Dr. Maria-E. Heisler-Wiegelmann hatte zusammen mit ihrem Ehemann Regionalkantor Thomas Wiegelmann am 25. Januar in Bad Orb ein Konzert mit Musik passend zum Titel \u201eWie sch\u00f6n leuchtet der Morgenstern\u201c gestaltet. Den Erl\u00f6s des Konzertes, 1200 Euro, konnten die S\u00e4ngerinnen und S\u00e4nger nun an den Malteser Hilfsdienst \u00fcbergeben. Schulleiter Thomas Wolf begr\u00fc\u00dfte den Pr\u00e4sidenten der Malteser Dr. Constantin von Brandenstein-Zeppelin in Anwesenheit der Gesch\u00e4ftsf\u00fchrer Bernward Bickmann und P. Udo Schm\u00e4lzle, der stellvertretenden Schulleiterin Andrea D\u00e4hn und des Fachbereichleiters Reinhold G\u00fcnther. Zu diesem Anlass hatte der Chor das St\u00fcck \u201eIch glaube\u201c von Udo J\u00fcrgens einstudiert, das inhaltlich gut zu diesem Anlass passte. Dr. Constantin von Brandenstein-Zeppelin nahm den Scheck dankend und mit gro\u00dfer Freude entgegen. <a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-07.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5088]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-5089\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-07-300x225.jpg\" alt=\"150311-Scheck\u00fcbergabe an Malteser-07\" width=\"199\" height=\"149\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-07-300x225.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-07-1024x768.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-07.jpg 1200w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a>Er berichtete auf packende und bewegende Art von der Arbeit des Hospizdienstes im Allgemeinen und der Arbeit der Helfer des Kinderhospizdienstes im Besonderen. Er verwies auf die Tatsache, dass diese Arbeit ausschlie\u00dflich von ehrenamtlichen Helfern geleistet werde, f\u00fcr deren Ausbildung und Betreuung man auf Spenden angewiesen sei. Danach informierte er die Anwesenden auch \u00fcber andere Arbeitsfelder der Malteser: Er stellte den Sch\u00fclerinnen und Sch\u00fcler die M\u00f6glichkeit vor, sich beispielsweise f\u00fcr ein paar Tage als Begleiter bei der j\u00e4hrlichen Lourdes-Wallfahrt f\u00fcr Menschen mit Behinderungen, durchgef\u00fchrt von den Maltesern in Kooperation mit den Bist\u00fcmern Fulda, Limburg und Mainz, zu engagieren, und lud sie ein, diese pers\u00f6nlich bereichernde Erfahrung einmal zu machen. Er berichtete dar\u00fcber hinaus auch vom Engagement der ehrenamtlichen Helfer in Senioreneinrichtungen, die mit regelm\u00e4\u00dfigen Besuchen die dort oft sp\u00fcrbare Einsamkeit einzelner Bewohner unterbrechen und ihnen Freude bringen k\u00f6nnen. Ein neues Aufgabenfeld ist die Betreuung von Demenzkranken, ein Arbeitsfeld, das immer st\u00e4rker in den Vordergrund r\u00fcckt.\r\n\u201eIch glaube Menschsein und es auch beweisen, das ist viel n\u00fctzlicher als jede Heldentat\u201c, so hei\u00dft es in dem Lied von Udo J\u00fcrgens. Dies selbst durch die Durchf\u00fchrung des Benefizkonzertes erfahren zu haben, war f\u00fcr die Sch\u00fclerinnen und Sch\u00fcler des Kammerchores ein besonderes Erlebnis, das sie neben der Begegnung mit dem Pr\u00e4sidenten der Malteser und dessen Ausf\u00fchrungen zu den Arbeitsfeldern des Hilfsdienstes sichtlich bewegt hat.<a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-20.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5088]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-5099\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-20-300x225.jpg\" alt=\"150311-Scheck\u00fcbergabe an Malteser-20\" width=\"268\" height=\"201\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-20-300x225.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-20-1024x768.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-20.jpg 1200w\" sizes=\"auto, (max-width: 268px) 100vw, 268px\" \/><\/a>\r\n\r\n<a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-15.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5088]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-5091\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-15-300x225.jpg\" alt=\"150311-Scheck\u00fcbergabe an Malteser-15\" width=\"247\" height=\"185\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-15-300x225.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-15-1024x768.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-15-440x330.jpg 440w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/150311-Scheck\u00fcbergabe-an-Malteser-15.jpg 1200w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><\/a>","protected":false},"excerpt":{"rendered":"Am Mittwoch, dem 11.3.2015, war Dr. Constantin von Brandenstein-Zeppelin, Pr\u00e4sident des Malteser Hilfsdienstes, Gast an unserer Schule. Anlass war die \u00dcbergabe einer Spende an den Kinderhospizdienst der Malteser. Der Kammerchor\u00a0 unter Leitung von Dr. Maria-E. Heisler-Wiegelmann hatte zusammen mit ihrem Ehemann Regionalkantor Thomas Wiegelmann am 25. Januar in Bad Orb ein Konzert mit Musik passend zum Titel \u201eWie sch\u00f6n leuchtet der Morgenstern\u201c gestaltet. Den Erl\u00f6s des Konzertes, 1200 Euro, konnten die S\u00e4ngerinnen und S\u00e4nger nun an den Malteser Hilfsdienst \u00fcbergeben. Schulleiter Thomas Wolf begr\u00fc\u00dfte den Pr\u00e4sidenten der Malteser Dr. Constantin von Brandenstein-Zeppelin in Anwesenheit der Gesch\u00e4ftsf\u00fchrer Bernward Bickmann und P. Udo Schm\u00e4lzle, der stellvertretenden Schulleiterin Andrea D\u00e4hn und des Fachbereichleiters Reinhold G\u00fcnther. Zu diesem Anlass hatte der Chor das St\u00fcck \u201eIch glaube\u201c von Udo J\u00fcrgens einstudiert, das inhaltlich gut zu diesem Anlass passte. Dr. Constantin von Brandenstein-Zeppelin nahm den Scheck dankend und mit gro\u00dfer Freude entgegen. Er berichtete auf packende und bewegende Art von der Arbeit des Hospizdienstes im Allgemeinen und der Arbeit der Helfer des Kinderhospizdienstes im Besonderen. Er verwies auf die Tatsache, dass diese Arbeit ausschlie\u00dflich von ehrenamtlichen Helfern geleistet werde, f\u00fcr deren Ausbildung und Betreuung man auf Spenden angewiesen sei. Danach informierte er die Anwesenden auch \u00fcber andere Arbeitsfelder der Malteser: Er stellte den Sch\u00fclerinnen und Sch\u00fcler die M\u00f6glichkeit vor, sich beispielsweise f\u00fcr ein paar Tage als Begleiter bei der j\u00e4hrlichen Lourdes-Wallfahrt f\u00fcr Menschen mit Behinderungen, durchgef\u00fchrt von den Maltesern in Kooperation mit den Bist\u00fcmern Fulda, Limburg und Mainz, zu engagieren, und lud sie ein, diese pers\u00f6nlich bereichernde Erfahrung einmal zu machen. Er berichtete dar\u00fcber hinaus auch vom Engagement der ehrenamtlichen Helfer in Senioreneinrichtungen, die mit regelm\u00e4\u00dfigen Besuchen die dort oft sp\u00fcrbare Einsamkeit einzelner Bewohner unterbrechen und ihnen Freude bringen k\u00f6nnen. Ein neues Aufgabenfeld ist die Betreuung von Demenzkranken, ein Arbeitsfeld, das immer st\u00e4rker in den Vordergrund r\u00fcckt. \u201eIch glaube Menschsein und es auch beweisen, das ist viel n\u00fctzlicher als jede Heldentat\u201c, so hei\u00dft es in dem Lied von Udo J\u00fcrgens. Dies selbst durch die Durchf\u00fchrung des Benefizkonzertes erfahren zu haben, war f\u00fcr die Sch\u00fclerinnen und Sch\u00fcler des Kammerchores ein besonderes Erlebnis, das sie neben der Begegnung mit dem Pr\u00e4sidenten der Malteser und dessen Ausf\u00fchrungen zu den Arbeitsfeldern des Hilfsdienstes sichtlich bewegt hat.","protected":false},"author":3,"featured_media":5091,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,252],"tags":[],"class_list":["post-5088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-fachbereich-1"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 20:33:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=5088"}],"version-history":[{"count":2,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5088\/revisions"}],"predecessor-version":[{"id":5100,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5088\/revisions\/5100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/5091"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=5088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=5088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=5088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}