{"id":5106,"date":"2015-03-17T14:31:31","date_gmt":"2015-03-17T13:31:31","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=5106"},"modified":"2016-02-17T13:31:06","modified_gmt":"2016-02-17T12:31:06","slug":"2-platz-im-regionalfinale-jugend-debattiert","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/2-platz-im-regionalfinale-jugend-debattiert\/","title":{"rendered":"Kreuzburg erfolgreich beim Regionalfinale Jugend debattiert"},"content":{"rendered":"Sieben Schulen im regionalen Schulverbund Hanau trafen sich am Dienstag, dem 24.2.2015 in der Otto-Hahn-Schule in Hanau, um ihre Vertreter f\u00fcr die n\u00e4chste Runde in dem bundesweiten Sch\u00fclerdebatten-Wettbewerb zu finden.\r\n\u201eJugend debattiert\u201c ist ein bundesweiter Redewettstreit, der von der Hertie Stiftung getragen wird. Das Projekt steht unter der Schirmherrschaft des Bundespr\u00e4sidenten, der j\u00e4hrlich vor den Sommerferien die Bundessieger aus Mittel- und Oberstufe in Berlin k\u00fcrt. Zu gewinnen gibt es ab dem Schulfinale zun\u00e4chst Buchpreise, sp\u00e4ter Rhetorikseminare auf der Burg Rothenfels. In der Bundeshauptstadt geht es dann im gro\u00dfen Sendesaal des Senders Radio Berlin Brandenburg um Sach- und Geldpreise. Mit Magdalena K.(2005) und Jens B. (2006) konnten sich in der Vergangenheit bereits zwei Kreuzburgsch\u00fcler f\u00fcr das Bundesfinale qualifizieren.\r\nIn der Otto-Hahn-Schule stand nun das Regionalfinale an. In Hin- und R\u00fcckrunde debattierten in Hanau um die Finalpl\u00e4tze die Kaufm\u00e4nnischen Schulen Hanau, die Karl-Rehbein-Schule Hanau, die Hohe Landesschule Hanau, die Albert-Einstein-Schule Maintal, das Franziskanergymnasium Kreuzburg Gro\u00dfkrotzenburg, das Einhardgymnasium Seligenstadt und die gastgebende Otto-Hahn- Schule Hanau. In Vierergruppen standen sich zu aktuellen gesellschaftlichen Themen jeweils zwei Debattanten mit unterschiedlicher Haltung gegen\u00fcber. Gegen durchweg \u00e4ltere Gegner aus h\u00f6heren Jahrg\u00e4ngen debattierten f\u00fcr unsere Schule Jennifer S. und Lukas N. aus der Jahrgangsstufe 10.\r\nDie Themen f\u00fcr die Vorrundendebatten lauteten: \u201eSoll bundesweit eine allgemeine Impfpflicht gegen Masern eingef\u00fchrt werden?\u201c und \u201eSollen von unserer Stadt mehr Fl\u00fcchtlinge aufgenommen werden?\u201c\r\nNach Einf\u00fchrungsrunde, freier Aussprache und Schlussrunde musste dann nach insgesamt 24 Minuten jeder Debattant seine Position in einem Zielsatz formulieren. Eine dreik\u00f6pfige Jury, begleitet von einem Zeitw\u00e4chter, bewertete dann die Sachkenntnis, die Ausdrucksf\u00e4higkeit, die Gespr\u00e4chsf\u00e4higkeit und die \u00dcberzeugungsf\u00e4higkeit eines jeden Redners.\r\n<a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/Jd-Siegerfoto-Regionalwettbewerb-2015-ausschnitt.jpg\" data-rel=fancybox rel=\"lightbox[5106]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-5107\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/Jd-Siegerfoto-Regionalwettbewerb-2015-ausschnitt-225x300.jpg\" alt=\"Jd-Siegerfoto Regionalwettbewerb 2015 ausschnitt\" width=\"225\" height=\"300\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/Jd-Siegerfoto-Regionalwettbewerb-2015-ausschnitt-225x300.jpg 225w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/03\/Jd-Siegerfoto-Regionalwettbewerb-2015-ausschnitt.jpg 465w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Ins Finale der Sekundarstufe II zogen f\u00fcr das Franziskanergymnasium Lukas N., Annalena L. von der Hohen Landesschule, Benedict K. von den Kaufm\u00e4nnischen Schulen und Sinah-Loreen H. von der Hohen Landesschule ein. Debattiert wurde die Frage: \u201eSollen in Deutschland Gigaliner f\u00fcr den \u00f6ffentlichen Stra\u00dfenverkehr zugelassen\r\nwerden?\u201c Die Erst- und Zweitplatzierten Annalena L. von der HoLa und Lukas N. von der Kreuzburg qualifizierten sich f\u00fcr die n\u00e4chste Zwischenstufe Hessen S\u00fcd, deren erste und zweite Sieger wiederum zum Hessenfinale fahren.\r\n<p style=\"text-align: right;\"><em>Michael Knedlik, Schulkoordinator Jugend debattiert<\/em><\/p>","protected":false},"excerpt":{"rendered":"Sieben Schulen im regionalen Schulverbund Hanau trafen sich am Dienstag, dem 24.2.2015 in der Otto-Hahn-Schule in Hanau, um ihre Vertreter f\u00fcr die n\u00e4chste Runde in dem bundesweiten Sch\u00fclerdebatten-Wettbewerb zu finden. \u201eJugend debattiert\u201c ist ein bundesweiter Redewettstreit, der von der Hertie Stiftung getragen wird. Das Projekt steht unter der Schirmherrschaft des Bundespr\u00e4sidenten, der j\u00e4hrlich vor den Sommerferien die Bundessieger aus Mittel- und Oberstufe in Berlin k\u00fcrt. Zu gewinnen gibt es ab dem Schulfinale zun\u00e4chst Buchpreise, sp\u00e4ter Rhetorikseminare auf der Burg Rothenfels. In der Bundeshauptstadt geht es dann im gro\u00dfen Sendesaal des Senders Radio Berlin Brandenburg um Sach- und Geldpreise. Mit Magdalena K.(2005) und Jens B. (2006) konnten sich in der Vergangenheit bereits zwei Kreuzburgsch\u00fcler f\u00fcr das Bundesfinale qualifizieren. In der Otto-Hahn-Schule stand nun das Regionalfinale an. In Hin- und R\u00fcckrunde debattierten in Hanau um die Finalpl\u00e4tze die Kaufm\u00e4nnischen Schulen Hanau, die Karl-Rehbein-Schule Hanau, die Hohe Landesschule Hanau, die Albert-Einstein-Schule Maintal, das Franziskanergymnasium Kreuzburg Gro\u00dfkrotzenburg, das Einhardgymnasium Seligenstadt und die gastgebende Otto-Hahn- Schule Hanau. In Vierergruppen standen sich zu aktuellen gesellschaftlichen Themen jeweils zwei Debattanten mit unterschiedlicher Haltung gegen\u00fcber. Gegen durchweg \u00e4ltere Gegner aus h\u00f6heren Jahrg\u00e4ngen debattierten f\u00fcr unsere Schule Jennifer S. und Lukas N. aus der Jahrgangsstufe 10. Die Themen f\u00fcr die Vorrundendebatten lauteten: \u201eSoll bundesweit eine allgemeine Impfpflicht gegen Masern eingef\u00fchrt werden?\u201c und \u201eSollen von unserer Stadt mehr Fl\u00fcchtlinge aufgenommen werden?\u201c Nach Einf\u00fchrungsrunde, freier Aussprache und Schlussrunde musste dann nach insgesamt 24 Minuten jeder Debattant seine Position in einem Zielsatz formulieren. Eine dreik\u00f6pfige Jury, begleitet von einem Zeitw\u00e4chter, bewertete dann die Sachkenntnis, die Ausdrucksf\u00e4higkeit, die Gespr\u00e4chsf\u00e4higkeit und die \u00dcberzeugungsf\u00e4higkeit eines jeden Redners. Ins Finale der Sekundarstufe II zogen f\u00fcr das Franziskanergymnasium Lukas N., Annalena L. von der Hohen Landesschule, Benedict K. von den Kaufm\u00e4nnischen Schulen und Sinah-Loreen H. von der Hohen Landesschule ein. Debattiert wurde die Frage: \u201eSollen in Deutschland Gigaliner f\u00fcr den \u00f6ffentlichen Stra\u00dfenverkehr zugelassen werden?\u201c Die Erst- und Zweitplatzierten Annalena L. von der HoLa und Lukas N. von der Kreuzburg qualifizierten sich f\u00fcr die n\u00e4chste Zwischenstufe Hessen S\u00fcd, deren erste und zweite Sieger wiederum zum Hessenfinale fahren. Michael Knedlik, Schulkoordinator Jugend debattiert","protected":false},"author":3,"featured_media":5109,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,252],"tags":[161],"class_list":["post-5106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-fachbereich-1","tag-jugend-debattiert"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:26:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=5106"}],"version-history":[{"count":6,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5106\/revisions"}],"predecessor-version":[{"id":5114,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5106\/revisions\/5114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/5109"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=5106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=5106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=5106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}