{"id":5634,"date":"2015-05-26T14:24:25","date_gmt":"2015-05-26T12:24:25","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=5634"},"modified":"2016-02-17T13:29:52","modified_gmt":"2016-02-17T12:29:52","slug":"bundeswettbewerb-fremdsprachen-201415-erfolg-im-fach-latein","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/bundeswettbewerb-fremdsprachen-201415-erfolg-im-fach-latein\/","title":{"rendered":"Bundeswettbewerb Fremdsprachen 2014\/15: Erfolg im Fach Latein"},"content":{"rendered":"<a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/05\/2015_04lateinehrung1.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5634]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-5636\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/05\/2015_04lateinehrung1-300x127.jpg\" alt=\"2015_04lateinehrung\" width=\"300\" height=\"127\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/05\/2015_04lateinehrung1-300x127.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/05\/2015_04lateinehrung1-1024x434.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/05\/2015_04lateinehrung1.jpg 1533w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ganz herzlich gratuliert die Fachschaft Latein Gideon B. (Jg. 12) zu seiner erneut erfolgreichen Teilnahme beim Bundeswettbewerb Fremdsprachen. Durch das erfolgreiche Abschneiden in der zweiten Runde &#8222;Solo 10+&#8220; im Fach Latein hat sich Gideon &#8211; wie bereits im Vorjahr &#8211; f\u00fcr die finale Runde, in der die besten Sch\u00fcler aller Fremdsprachen miteinander konkurrieren und die auf Bundesebene im September 2015 in Bad Honnef durchgef\u00fchrt wird, qualifiziert. Diese Endrunde haben von 240 Teilnehmern der zweiten Runde lediglich 48 Sch\u00fcler erreicht.\r\nWir w\u00fcnschen Gideon hierf\u00fcr viel Erfolg!\r\n\r\n<em>Auf dem Foto Gideon stehend mit Schulleiter Thomas Wolf und Lateinlehrer Rainer Sch\u00e4fer bei der \u00dcberreichung der Siegerurkunde im Lateinunterricht.<\/em>","protected":false},"excerpt":{"rendered":"Ganz herzlich gratuliert die Fachschaft Latein Gideon B. (Jg. 12) zu seiner erneut erfolgreichen Teilnahme beim Bundeswettbewerb Fremdsprachen. Durch das erfolgreiche Abschneiden in der zweiten Runde &#8222;Solo 10+&#8220; im Fach Latein hat sich Gideon &#8211; wie bereits im Vorjahr &#8211; f\u00fcr die finale Runde, in der die besten Sch\u00fcler aller Fremdsprachen miteinander konkurrieren und die auf Bundesebene im September 2015 in Bad Honnef durchgef\u00fchrt wird, qualifiziert. Diese Endrunde haben von 240 Teilnehmern der zweiten Runde lediglich 48 Sch\u00fcler erreicht. Wir w\u00fcnschen Gideon hierf\u00fcr viel Erfolg! Auf dem Foto Gideon stehend mit Schulleiter Thomas Wolf und Lateinlehrer Rainer Sch\u00e4fer bei der \u00dcberreichung der Siegerurkunde im Lateinunterricht.","protected":false},"author":3,"featured_media":5635,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,252],"tags":[],"class_list":["post-5634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-fachbereich-1"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:52:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=5634"}],"version-history":[{"count":2,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5634\/revisions"}],"predecessor-version":[{"id":5638,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5634\/revisions\/5638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/5635"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=5634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=5634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=5634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}