{"id":5906,"date":"2015-06-29T12:27:30","date_gmt":"2015-06-29T10:27:30","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=5906"},"modified":"2016-02-17T13:29:01","modified_gmt":"2016-02-17T12:29:01","slug":"small-talk-mit-her-majesty","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/small-talk-mit-her-majesty\/","title":{"rendered":"Small-Talk mit Her Majesty"},"content":{"rendered":"<div id=\"attachment_5909\" style=\"width: 247px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch1.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5906]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5909\" class=\"wp-image-5909\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch1-300x200.jpg\" alt=\"2015_06queenbesuch1\" width=\"237\" height=\"158\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch1-300x200.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch1-1024x684.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch1.jpg 1200w\" sizes=\"auto, (max-width: 237px) 100vw, 237px\" \/><\/a><p id=\"caption-attachment-5909\" class=\"wp-caption-text\">\u00a9Hessische Staatskanzlei \/ Sabrina Feige<\/p><\/div>\r\n\r\nSpannung liegt in der Luft. Unsichere Blicke. Ein\u00fcben von kleinen Verbeugungen und Knicksen. Nerv\u00f6ses Richten von Frisur und Kleidung. Sich wiederholendes Fl\u00fcstern von \u201cYour Majesty. Your Royal Highness.\u201d Selten war Englisch-Unterricht wohl mit so viel Anspannung verbunden wie bei den 16 Sch\u00fclern des Franziskanergymnasiums Kreuzburg, die am vergangen Donnerstag die englische Monarchie live in Frankfurt erleben durften.\r\n\r\n<a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch2.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5906]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-5910 \" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch2-300x225.jpg\" alt=\"\" width=\"257\" height=\"193\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch2-300x225.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch2-1024x768.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch2.jpg 1200w\" sizes=\"auto, (max-width: 257px) 100vw, 257px\" \/><\/a>\r\n\r\n\u201eEigentlich war alles nur eine spontane Idee\u201c, erkl\u00e4rt Julian S\u00fc\u00df lachend, der Lehrer des Englisch-Kurses. Im Unterricht sei die britische Regierungserkl\u00e4rung behandelt worden und in dieser spricht Queen Elizabeth II. von ihrer Vorfreude auf den Staatsbesuch nach Deutschland. Also schrieben die Sch\u00fcler des Kurses ein Bewerbungsschreiben an den britischen Botschafter in Berlin und den Frankfurter B\u00fcrgermeister. Eine Woche vor dem Besuch kam dann \u00fcberraschend die Zusage der hessischen Staatsregierung.\r\n\r\n<div id=\"attachment_5907\" style=\"width: 262px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5906]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5907\" class=\"  wp-image-5907\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch-300x200.jpg\" alt=\"2015_06queenbesuch\" width=\"252\" height=\"168\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch-300x200.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch-1024x684.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch.jpg 1200w\" sizes=\"auto, (max-width: 252px) 100vw, 252px\" \/><\/a><p id=\"caption-attachment-5907\" class=\"wp-caption-text\">\u00a9Hessische Staatskanzlei \/ Sabrina Feige<\/p><\/div>\r\n\r\nDoch wie der Besuch tats\u00e4chlich ablief, habe sich vorab niemand ertr\u00e4umen lassen, meint der 17-j\u00e4hrige Clemens B.. Denn die Jugendlichen durften sogar ein paar Worte mit dem Staatsoberhaupt wechseln: \u201eSie fragte uns, welche Schule wir besuchten\u201c, berichtet Carlotta I., die die Frage auch beantwortete. Prinz Philip habe sogar auf Deutsch mit den Sch\u00fclern geplaudert. Auch Bundespr\u00e4sident Gauck und seine aus Hanau stammende Lebensgef\u00e4hrtin unterhielten sich im Rahmen des Besuchs in der Paulkirche mit den Sch\u00fclern. \u201eIhr k\u00f6nnt euch gl\u00fccklich sch\u00e4tzen, hier zu sein\u201c, betonte dabei Ministerpr\u00e4sident Volker Bouffier und fasste damit die Stimmung gut zusammen.\r\nPolizeibegleitung, strenge Protokollvorschriften, Live-\u00dcbertragung im Fernsehen, Pressefotos mit der Queen, Frontposition bei den 120 geladenen G\u00e4sten \u2013 die Liste der einmaligen Erlebnisse dieses Tages ist lang, doch am eindrucksvollsten fanden die Sch\u00fcler eindeutig die k\u00f6niglichen Hoheiten selbst. \u201ePrinz Philip war richtig gut aufgelegt\u201c, erz\u00e4hlt Tara S. und \u201edie Queen wirkte echt sympathisch\u201c, best\u00e4tigt ihr Mitsch\u00fcler Frederik P. Dass dieser Tag f\u00fcr immer im Ged\u00e4chtnis behalten wird, scheint bei diesen Berichten offensichtlich.<a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch3.jpg\" data-rel=\"fancybox\" rel=\"lightbox[5906]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-5912\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch3-300x169.jpg\" alt=\"2015_06queenbesuch3\" width=\"234\" height=\"132\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch3-300x169.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch3-1024x576.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2015\/06\/2015_06queenbesuch3.jpg 1300w\" sizes=\"auto, (max-width: 234px) 100vw, 234px\" \/><\/a>\r\n\r\nEin Bericht von Sch\u00fclern zum Besuch <a href=\"http:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?wpdmdl=5916\">hier<\/a>.","protected":false},"excerpt":{"rendered":"Spannung liegt in der Luft. Unsichere Blicke. Ein\u00fcben von kleinen Verbeugungen und Knicksen. Nerv\u00f6ses Richten von Frisur und Kleidung. Sich wiederholendes Fl\u00fcstern von \u201cYour Majesty. Your Royal Highness.\u201d Selten war Englisch-Unterricht wohl mit so viel Anspannung verbunden wie bei den 16 Sch\u00fclern des Franziskanergymnasiums Kreuzburg, die am vergangen Donnerstag die englische Monarchie live in Frankfurt erleben durften. \u201eEigentlich war alles nur eine spontane Idee\u201c, erkl\u00e4rt Julian S\u00fc\u00df lachend, der Lehrer des Englisch-Kurses. Im Unterricht sei die britische Regierungserkl\u00e4rung behandelt worden und in dieser spricht Queen Elizabeth II. von ihrer Vorfreude auf den Staatsbesuch nach Deutschland. Also schrieben die Sch\u00fcler des Kurses ein Bewerbungsschreiben an den britischen Botschafter in Berlin und den Frankfurter B\u00fcrgermeister. Eine Woche vor dem Besuch kam dann \u00fcberraschend die Zusage der hessischen Staatsregierung. Doch wie der Besuch tats\u00e4chlich ablief, habe sich vorab niemand ertr\u00e4umen lassen, meint der 17-j\u00e4hrige Clemens B.. Denn die Jugendlichen durften sogar ein paar Worte mit dem Staatsoberhaupt wechseln: \u201eSie fragte uns, welche Schule wir besuchten\u201c, berichtet Carlotta I., die die Frage auch beantwortete. Prinz Philip habe sogar auf Deutsch mit den Sch\u00fclern geplaudert. Auch Bundespr\u00e4sident Gauck und seine aus Hanau stammende Lebensgef\u00e4hrtin unterhielten sich im Rahmen des Besuchs in der Paulkirche mit den Sch\u00fclern. \u201eIhr k\u00f6nnt euch gl\u00fccklich sch\u00e4tzen, hier zu sein\u201c, betonte dabei Ministerpr\u00e4sident Volker Bouffier und fasste damit die Stimmung gut zusammen. Polizeibegleitung, strenge Protokollvorschriften, Live-\u00dcbertragung im Fernsehen, Pressefotos mit der Queen, Frontposition bei den 120 geladenen G\u00e4sten \u2013 die Liste der einmaligen Erlebnisse dieses Tages ist lang, doch am eindrucksvollsten fanden die Sch\u00fcler eindeutig die k\u00f6niglichen Hoheiten selbst. \u201ePrinz Philip war richtig gut aufgelegt\u201c, erz\u00e4hlt Tara S. und \u201edie Queen wirkte echt sympathisch\u201c, best\u00e4tigt ihr Mitsch\u00fcler Frederik P. Dass dieser Tag f\u00fcr immer im Ged\u00e4chtnis behalten wird, scheint bei diesen Berichten offensichtlich. Ein Bericht von Sch\u00fclern zum Besuch hier.","protected":false},"author":3,"featured_media":5907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,252],"tags":[],"class_list":["post-5906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-fachbereich-1"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:35:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=5906"}],"version-history":[{"count":4,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5906\/revisions"}],"predecessor-version":[{"id":5918,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/5906\/revisions\/5918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/5907"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=5906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=5906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=5906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}