{"id":9324,"date":"2016-07-12T16:05:57","date_gmt":"2016-07-12T14:05:57","guid":{"rendered":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/?p=9324"},"modified":"2016-07-12T16:44:46","modified_gmt":"2016-07-12T14:44:46","slug":"zusammenarbeit-zwischen-schule-und-universitaet-unterzeichnung-des-kooperationsvertrages-beim-sommerfest","status":"publish","type":"post","link":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/zusammenarbeit-zwischen-schule-und-universitaet-unterzeichnung-des-kooperationsvertrages-beim-sommerfest\/","title":{"rendered":"Zusammenarbeit zwischen Schule und Universit\u00e4t  &#8211;  Unterzeichnung des Kooperationsvertrages beim Sommerfest"},"content":{"rendered":"<a attid=\"9325\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest07.jpg\" data-rel=fancybox rel=\"lightbox[9324]\"><img decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest07-300x225.jpg\" alt=\"2016_07_10sommerfest07\" width=\"200\"  class=\"alignright size-medium wp-image-9325\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest07-300x225.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest07-768x576.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest07-1024x768.jpg 1024w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest07.jpg 1296w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u201eNicht gestern und nicht morgen, sondern nur um heute soll es gehen, wenn wir unser Sommerfest zum Schuljahresende feiern, k\u00fcndigte Bruder Michael Blasek ofm am vergangenen Sonntag im Gottesdienst am Franziskanergymnasium Kreuzburg an. Bei der abschlie\u00dfenden Feststunde an diesem Tag ging es allerdings auch um das Gestern und Morgen, denn den H\u00f6hepunkt der Veranstaltung bildete die Unterzeichnung des Kooperationsvertrages mit der Goethe-Universit\u00e4t Frankfurt.<br>\r\n<a attid=\"9328\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest30.jpg\"d ata-rel=fancybox rel=\"lightbox[9324]\"><img decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest30-300x177.jpg\" alt=\"2016_07_10sommerfest30\" width=\"200\"  class=\"alignleft size-medium wp-image-9328\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest30-300x177.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest30-768x453.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest30-1024x604.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Zur Unterzeichnung des Vertrages, in dem die geplante zuk\u00fcnftige Zusammenarbeit zwischen der Schule und der Universit\u00e4t festgehalten ist, war die Vizepr\u00e4sidentin der Universit\u00e4t Prof. Dr. Tanja Br\u00fchl angereist. Sie zeigte sich beeindruckt von den Angeboten der Schule vor allem im Freien Lernbereich. Den Kooperationsvertrag sieht sie als positive Entwicklung, da es im Interesse der Universit\u00e4t sei, \u201egute Studenten\u201c zu bekommen. Schulleiter Thomas Wolf erl\u00e4uterte, worum es in dem Kooperationsvertrag geht. Die geplante Gemeinschaft betrifft viele Bereiche, so sei die Universit\u00e4t Ansprechpartner in unterrichtlichen Fragen f\u00fcr die Fachbereiche und kann die Fortbildung der Lehrkr\u00e4fte unterst\u00fctzen. Besonders im Bereich der Forschungsprojekte im Freien Lernbereich, in der Begabungsf\u00f6rderung und f\u00fcr das Sch\u00fclerstudium gibt es Angebote von der Universit\u00e4t und sie steht f\u00fcr gezielte Berufsberatungen zur Verf\u00fcgung. Das Gymnasium hatte bereits im vergangenen Schuljahr vier Lehramtsstudenten zum Praktikum aufgenommen und wird dies in Zukunft regelm\u00e4\u00dfig tun. <br>\r\n<a attid=\"9327\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest41.jpg\" data-rel=fancybox rel=\"lightbox[9324]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest41-300x105.jpg\" alt=\"2016_07_10sommerfest41\" width=\"300\" height=\"105\" class=\"alignleft size-medium wp-image-9327\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest41-300x105.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest41-768x270.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest41-1024x360.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Um das Gestern ging es in der Feststunde bei den Ehrungen zu erfolgreichen Leistungen im vergangenen Schuljahr. Sch\u00fcler der Kreuzburg hatten wiederholt erfolgreich am Bundeswettbewerb Fremdsprachen im Fach Latein teilgenommen. Besonders hervorgehoben wurden hierbei die Latein-AG unter der Leitung von Carmen Weipert, die mit ihrem Theaterst\u00fcck \u201ePyramus und Thisbe\u201c bei dem Wettbewerb den zweiten Platz in Hessen erzielte, sowie Julian Kaiser, der im Einzelwettbewerb den zweiten Platz erreichte. F\u00fcr die Besucher des Sommerfestes wurde das siegreiche Theaterst\u00fcck nochmals in einem Film vorgef\u00fchrt.<br>\r\n<a attid=\"9329\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest34.jpg\" data-rel=fancybox rel=\"lightbox[9324]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest34-300x104.jpg\" alt=\"2016_07_10sommerfest34\" width=\"300\" height=\"104\" class=\"alignright size-medium wp-image-9329\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest34-300x104.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest34-768x266.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07_10sommerfest34-1024x355.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Zur Unterhaltung trugen auch die Vorf\u00fchrungen der Tanz-AGs unter Leitung von Carina Grimm und Iris Stickelmayer-Buchheim bei. Beide AGs konnten sich in diesem Jahr bei Jugend trainiert f\u00fcr Olympia gut platzieren. Besonders begl\u00fcckw\u00fcnschte der Schulleiter Annika Schilling und Sarah Walter, die sich im Wettbewerb den ersten Platz als bestes Einzelpaar unter 99 im Langsamen Walzer und in der Cha-Cha-Cha ertanzt hatten.\r\n<a attid=\"9330\"  href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07sommerfest65.jpg\" data-rel=fancybox rel=\"lightbox[9324]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07sommerfest65-300x200.jpg\" alt=\"2016_07sommerfest65\" width=\"300\" height=\"200\" class=\"alignright size-medium wp-image-9330\" srcset=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07sommerfest65-300x200.jpg 300w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07sommerfest65-768x512.jpg 768w, https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-content\/uploads\/2016\/07\/2016_07sommerfest65-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\r\n<br>Aber nach dem Motto des Gottesdienstes ging es ja vor allem um das \u201eheute\u201c beim Sommerfest und dieses konnten die zahlreichen Besucher aus den Klassenfamilien bei strahlend sch\u00f6nem Wetter genie\u00dfen. Die Cafeteria sorgte mit Speisen vom Grill f\u00fcr das leibliche Wohl und so sa\u00dfen die Klassenfamilien zwischen Schule, Kloster und dem Bildungswerk gem\u00fctlich beisammen. Um die Unterhaltung im Freien hatten sich einige Klassen gek\u00fcmmert: das Programm reichte dabei von Armbandflechten \u00fcber Kinderschminken und Torwandschie\u00dfen bis zu Wikingerschach. Die Eine-Welt-Gruppe und der Arbeitskreis Umwelt und Gesundheit informierten \u00fcber ihre Projekte.<br>\r\nBruder Michael gab des Besuchern des Festes mit auf den Weg, man solle es in der Urlaubszeit vielleicht einmal mit den 10 Geboten der Gelassenheit von Papst Johannes XXIII. probieren und k\u00f6nne damit zu mehr Ausgeglichenheit, Aufmerksamkeit, Sensibilit\u00e4t und letztlich zu Dankbarkeit kommen.\r\nWeitere Fotos <a href=\"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/galerie\/nggallery\/fotos\/Sommerfest-2016\">hier.<\/a>","protected":false},"excerpt":{"rendered":"\u201eNicht gestern und nicht morgen, sondern nur um heute soll es gehen, wenn wir unser Sommerfest zum Schuljahresende feiern, k\u00fcndigte Bruder Michael Blasek ofm am vergangenen Sonntag im Gottesdienst am Franziskanergymnasium Kreuzburg an. Bei der abschlie\u00dfenden Feststunde an diesem Tag ging es allerdings auch um das Gestern und Morgen, denn den H\u00f6hepunkt der Veranstaltung bildete die Unterzeichnung des Kooperationsvertrages mit der Goethe-Universit\u00e4t Frankfurt. Zur Unterzeichnung des Vertrages, in dem die geplante zuk\u00fcnftige Zusammenarbeit zwischen der Schule und der Universit\u00e4t festgehalten ist, war die Vizepr\u00e4sidentin der Universit\u00e4t Prof. Dr. Tanja Br\u00fchl angereist. Sie zeigte sich beeindruckt von den Angeboten der Schule vor allem im Freien Lernbereich. Den Kooperationsvertrag sieht sie als positive Entwicklung, da es im Interesse der Universit\u00e4t sei, \u201egute Studenten\u201c zu bekommen. Schulleiter Thomas Wolf erl\u00e4uterte, worum es in dem Kooperationsvertrag geht. Die geplante Gemeinschaft betrifft viele Bereiche, so sei die Universit\u00e4t Ansprechpartner in unterrichtlichen Fragen f\u00fcr die Fachbereiche und kann die Fortbildung der Lehrkr\u00e4fte unterst\u00fctzen. Besonders im Bereich der Forschungsprojekte im Freien Lernbereich, in der Begabungsf\u00f6rderung und f\u00fcr das Sch\u00fclerstudium gibt es Angebote von der Universit\u00e4t und sie steht f\u00fcr gezielte Berufsberatungen zur Verf\u00fcgung. Das Gymnasium hatte bereits im vergangenen Schuljahr vier Lehramtsstudenten zum Praktikum aufgenommen und wird dies in Zukunft regelm\u00e4\u00dfig tun. Um das Gestern ging es in der Feststunde bei den Ehrungen zu erfolgreichen Leistungen im vergangenen Schuljahr. Sch\u00fcler der Kreuzburg hatten wiederholt erfolgreich am Bundeswettbewerb Fremdsprachen im Fach Latein teilgenommen. Besonders hervorgehoben wurden hierbei die Latein-AG unter der Leitung von Carmen Weipert, die mit ihrem Theaterst\u00fcck \u201ePyramus und Thisbe\u201c bei dem Wettbewerb den zweiten Platz in Hessen erzielte, sowie Julian Kaiser, der im Einzelwettbewerb den zweiten Platz erreichte. F\u00fcr die Besucher des Sommerfestes wurde das siegreiche Theaterst\u00fcck nochmals in einem Film vorgef\u00fchrt. Zur Unterhaltung trugen auch die Vorf\u00fchrungen der Tanz-AGs unter Leitung von Carina Grimm und Iris Stickelmayer-Buchheim bei. Beide AGs konnten sich in diesem Jahr bei Jugend trainiert f\u00fcr Olympia gut platzieren. Besonders begl\u00fcckw\u00fcnschte der Schulleiter Annika Schilling und Sarah Walter, die sich im Wettbewerb den ersten Platz als bestes Einzelpaar unter 99 im Langsamen Walzer und in der Cha-Cha-Cha ertanzt hatten. Aber nach dem Motto des Gottesdienstes ging es ja vor allem um das \u201eheute\u201c beim Sommerfest und dieses konnten die zahlreichen Besucher aus den Klassenfamilien bei strahlend sch\u00f6nem Wetter genie\u00dfen. Die Cafeteria sorgte mit Speisen vom Grill f\u00fcr das leibliche Wohl und so sa\u00dfen die Klassenfamilien zwischen Schule, Kloster und dem Bildungswerk gem\u00fctlich beisammen. Um die Unterhaltung im Freien hatten sich einige Klassen gek\u00fcmmert: das Programm reichte dabei von Armbandflechten \u00fcber Kinderschminken und Torwandschie\u00dfen bis zu Wikingerschach. Die Eine-Welt-Gruppe und der Arbeitskreis Umwelt und Gesundheit informierten \u00fcber ihre Projekte. Bruder Michael gab des Besuchern des Festes mit auf den Weg, man solle es in der Urlaubszeit vielleicht einmal mit den 10 Geboten der Gelassenheit von Papst Johannes XXIII. probieren und k\u00f6nne damit zu mehr Ausgeglichenheit, Aufmerksamkeit, Sensibilit\u00e4t und letztlich zu Dankbarkeit kommen. Weitere Fotos hier.","protected":false},"author":3,"featured_media":9326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[213],"class_list":["post-9324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-gottesdienst"],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:01:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/9324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/comments?post=9324"}],"version-history":[{"count":8,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/9324\/revisions"}],"predecessor-version":[{"id":9423,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/posts\/9324\/revisions\/9423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media\/9326"}],"wp:attachment":[{"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/media?parent=9324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/categories?post=9324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franziskanergymnasium-kreuzburg.de\/cms\/wp-json\/wp\/v2\/tags?post=9324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}